{"id":1161,"date":"2024-07-25T17:03:50","date_gmt":"2024-07-25T15:03:50","guid":{"rendered":"https:\/\/www.uni.lu\/lcsb-fr\/?post_type=news&#038;p=1161"},"modified":"2024-11-06T10:24:10","modified_gmt":"2024-11-06T09:24:10","slug":"passerelles-entre-cellules-pour-cerveau-en-bonne-sante","status":"publish","type":"news","link":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/","title":{"rendered":"Des passerelles entre les cellules pour un cerveau en bonne sant\u00e9"},"content":{"rendered":"\n<section class=\"wp-block-unilux-blocks-free-section section\"><div class=\"container xl:max-w-screen-xl\">\n<p>Le cerveau contient de nombreux types de cellules, des neurones dont nous avons tous entendu parler aux cellules microgliales, moins connues du grand public. Ces derni\u00e8res jouent pourtant un r\u00f4le crucial&nbsp;: elles font partie int\u00e9grante du syst\u00e8me immunitaire du cerveau et y font en quelque sorte office de service de nettoyage. Une \u00e9tude r\u00e9cente men\u00e9e par des chercheurs de l&rsquo;<a href=\"https:\/\/www.ukbonn.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">H\u00f4pital universitaire de Bonn<\/a> et du <a href=\"https:\/\/www.uni.lu\/lcsb-fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Luxembourg Centre for Systems Biomedicine<\/a> (LCSB) de l&rsquo;Universit\u00e9 du Luxembourg, en collaboration avec des scientifiques fran\u00e7ais, hongrois et allemands montre que ces cellules microgliales \u00e9tablissent des connexions avec les neurones par l&rsquo;interm\u00e9diaire de nanotubes \u00e0 effet tunnel. Elles utilisent ces minces tubes pour \u00e9liminer les prot\u00e9ines toxiques qui s\u2019accumulent \u00e0 l\u2019int\u00e9rieur des neurones, contribuant ainsi \u00e0 am\u00e9liorer la sant\u00e9 des neurones. Ces r\u00e9sultats, <a href=\"https:\/\/www.cell.com\/neuron\/fulltext\/S0896-6273(24)00491-4\" target=\"_blank\" rel=\"noreferrer noopener\">publi\u00e9s dans la revue scientifique <em>Neuron<\/em><\/a>, sugg\u00e8rent que ce m\u00e9canisme joue un r\u00f4le essentiel dans la lutte contre la neurod\u00e9g\u00e9n\u00e9rescence.<br><br>Une accumulation anormale de prot\u00e9ines est une caract\u00e9ristique de plusieurs troubles neurod\u00e9g\u00e9n\u00e9ratifs, dont la maladie d&rsquo;Alzheimer, la d\u00e9mence fronto-temporale et la maladie de Parkinson. Des prot\u00e9ines telles que l&rsquo;alpha-synucl\u00e9ine et la tau peuvent s&rsquo;agr\u00e9ger \u00e0 l&rsquo;int\u00e9rieur des neurones, perturbant ainsi le fonctionnement cellulaire. \u00ab Nous savions que les cellules microgliales jouaient un r\u00f4le dans l&rsquo;\u00e9limination de ces agr\u00e9gats de prot\u00e9ines mais ce n&rsquo;est que r\u00e9cemment que nous avons appris qu&rsquo;elle pouvait former des nanotubes \u00e0 effet tunnel, de longues extensions capables de relier des cellules \u00e9loign\u00e9es dans le cerveau, \u00bb explique le <a href=\"https:\/\/www.uni.lu\/lcsb-en\/people\/michael-heneka\/\" target=\"_blank\" rel=\"noreferrer noopener\">professeur Michael Heneka<\/a>, directeur du LCSB, responsable de l\u2019\u00e9quipe <a href=\"https:\/\/www.uni.lu\/lcsb-en\/research-groups\/neuroinflammation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Neuroinflammation<\/a> et auteur principal de l&rsquo;article. \u00ab Avec cette \u00e9tude, nous voulions mieux comprendre le transfert de mat\u00e9riel biologique entre les neurones et les cellules microgliales via ces nanotubes et explorer les cons\u00e9quences de cet \u00e9change pour la sant\u00e9 cellulaire. \u00bb<br><br>En utilisant des cultures de neurones et de cellules microgliales, issues de souris ou d\u00e9riv\u00e9es de cellules souches humaines, ainsi que de la microscopie de pointe, les chercheurs ont montr\u00e9 que les cellules microgliales \u00e9tablissent un contact avec les neurones par l&rsquo;interm\u00e9diaire des nanotubes \u00e0 effet tunnel (TNT). Cela leur permet de d\u00e9barrasser les neurones affect\u00e9s des agr\u00e9gats de prot\u00e9ines toxiques et de leur transf\u00e9rer \u00e9galement des mitochondries, les centrales \u00e9nerg\u00e9tiques des cellules. Ce double \u00e9change a pour effet de r\u00e9duire consid\u00e9rablement le stress oxydatif des neurones, de r\u00e9tablir leur fonctionnement normal et de prot\u00e9ger ainsi ces cellules nerveuses.<\/p>\n\n\n\n<h4 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"observer-la-formation-de-nanotubes-en-direct\"\n    >\nObserver la formation de nanotubes en direct<\/h4>\n\n\n\n<p>En utilisant une technique d\u2019imagerie sur cellules vivantes, les scientifiques ont observ\u00e9 la formation de connexions entre les neurones et les cellules microgliales. \u00ab Des travaux de recherche compl\u00e9mentaires seront n\u00e9cessaires pour comprendre en d\u00e9tails la formation et le fonctionnement de ces TNTs mais c\u2019est vraiment passionnant de voir que les cellules microgliales jouent un r\u00f4le actif dans la sant\u00e9 des neurones et peuvent leur venir en aide en cas de besoin, \u00bb d\u00e9taille <a href=\"https:\/\/www.age.mpg.de\/person\/133115\/2930\" target=\"_blank\" rel=\"noreferrer noopener\">Dr Hannah Scheiblich<\/a>, premier auteur de l\u2019article qui a travaill\u00e9 avec le professeur Heneka \u00e0 l&rsquo;<a href=\"https:\/\/www.ukbonn.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">H\u00f4pital universitaire de Bonn<\/a> et au <a href=\"https:\/\/www.dzne.de\/en\/\" target=\"_blank\" rel=\"noreferrer noopener\">German Center for Neurodegenerative Diseases<\/a>.<\/p>\n\n\n<div class=\"thumbnail  wp-block-unilux-blocks-thumbnail-video-vimeo\">\n    <span class=\"thumbnail__container\">\n        <span class=\"thumbnail__body\">\n            <span class=\"icon-rounded p-24 shadow bg-theme\">\n                <svg aria-hidden=\"true\" focusable=\"false\" class=\"icon icon-solid icon--play icon--white\"><use xlink:href=\"https:\/\/www.uni.lu\/wp-content\/themes\/unilux-theme\/assets\/images\/icons\/icons-solid.svg#icon--play\"><\/use><\/svg>            <\/span>\n        <\/span>\n        <figure class=\"wp-block-dev4-reusable-blocks-image w-full object-fit--cover\">\n    \n<img decoding=\"async\" class=\"wp-block-image unilux-custom-image-block\"\n                alt=\"\"\n            src=\"https:\/\/vumbnail.com\/989990004.jpg\"\n                    style=\"object-position: 28.00% 49.00%; font-family: &quot;object-fit: cover; object-position: 28.00% 49.00%;&quot;; aspect-ratio: 4\/3; object-fit: cover; width: 100%;\"\n        loading=\"lazy\"\n\/>    <\/figure>    <\/span>\n    \n<div class=\"modal fade vimeo-modal wp-block-unilux-blocks-thumbnail-video-vimeo\" id=\"modal-fvO9Z\" tabindex=\"-1\">\n    <div class=\"modal-dialog modal-dialog-centered modal-dialog-scrollable\">\n        <div class=\"modal-content\">\n            \n<div class=\"modal-header\">\n    <div class=\"modal-title\">\n        <h1 id=\"modal-filter-title\">Thumbnail Video<\/h1>\n    <\/div>\n    <button type=\"button\" class=\"modal__btn-close\" data-bs-dismiss=\"modal\">\n        <span class=\"modal__btn-close__name\">Fermer<\/span>\n    <\/button>\n<\/div>\n            \n<style>\n    .modal-body {\n        padding: 0 !important;\n        flex: auto;\n    }\n<\/style>\n<div class=\"modal-body\">\n    <div class=\"vimeo-video\" data-video-url=\"https:\/\/player.vimeo.com\/video\/989990004?h=\"><\/div><\/div>\n\n                    <\/div>\n    <\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-left\"><sup>La vid\u00e9o ci-dessus montre la formation de TNTs entre un neurone et des cellules microgliales, et le transfert d&rsquo;agr\u00e9gats d&rsquo;alpha-synucl\u00e9ine (fl\u00e8che rouge) dans des cellules vivantes.<\/sup><br><sup>Cette vid\u00e9o a \u00e9t\u00e9 film\u00e9e \u00e0 l&rsquo;aide d\u2019une technique d\u2019imagerie sur cellules vivantes in vitro.<\/sup><\/p>\n\n\n\n<h4 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"les-cellules-microgliales-a-la-rescousse-des-neurones\"\n    >\n<strong>Les cellules microgliales \u00e0 la rescousse des neurones<\/strong><\/h4>\n\n\n\n<p>En mettant en culture de neurones avec des cellules microgliales, l&rsquo;\u00e9quipe a observ\u00e9 que lorsque les prot\u00e9ines toxiques s&rsquo;accumulent au sein des neurones, le nombre de TNT reliant les deux types de cellules augmente et que ces nanotubes contiennent des particules d&rsquo;alpha-synucl\u00e9ine et de prot\u00e9ine tau. Ces agr\u00e9gats toxiques \u00e9taient uniquement transf\u00e9r\u00e9s des neurones aux cellules microgliales, et non l&rsquo;inverse, et \u00e9taient ensuite d\u00e9grad\u00e9s par les cellules microgliales. Les r\u00e9sultats obtenus ont non seulement montr\u00e9 que les cellules microgliales peuvent soulager efficacement les neurones affect\u00e9s par l\u2019accumulation de prot\u00e9ines toxiques mais qu&rsquo;elles leur transf\u00e8rent \u00e9galement des mitochondries par le biais des m\u00eames TNT.<\/p>\n\n\n\n<p>Les mitochondries sont des composants importants des cellules et lorsqu&rsquo;elles ne fonctionnent pas correctement, il peut en r\u00e9sulter des d\u00e9ficits \u00e9nerg\u00e9tiques et un stress oxydatif. L&rsquo;alpha-synucl\u00e9ine et la prot\u00e9ine tau peuvent alt\u00e9rer le fonctionnement des mitochondries, contribuant par ce biais au processus neurod\u00e9g\u00e9n\u00e9ratif. De mani\u00e8re remarquable, les chercheurs ont constat\u00e9 que lorsque les cellules microgliales transf\u00e8rent des mitochondries saines aux neurones affect\u00e9s, cela r\u00e9tablit la production d&rsquo;\u00e9nergie et r\u00e9duit les dommages oxydatifs, pr\u00e9servant ainsi efficacement le fonctionnement des neurones et assurant leur survie.<br><br>Dans l&rsquo;ensemble, ces r\u00e9sultats sugg\u00e8rent qu&rsquo;en \u00e9liminant les agr\u00e9gats de prot\u00e9ines et en transf\u00e9rant des mitochondries fonctionnelles vers les neurones, les cellules microgliales et leurs nanotubes favorise la bonne sant\u00e9 des cellules nerveuses et peuvent ralentir la progression de la neurod\u00e9g\u00e9n\u00e9rescence.<\/p>\n\n\n\n<h4 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"explorer-limpact-de-certaines-mutations-genetiques\"\n    >\n<strong>Explorer l&rsquo;impact de certaines mutations g\u00e9n\u00e9tiques<\/strong><\/h4>\n\n\n\n<p>Les chercheurs ont ensuite examin\u00e9 si diff\u00e9rentes mutations g\u00e9n\u00e9tiques associ\u00e9es aux maladies neurod\u00e9g\u00e9n\u00e9ratives avaient un impact sur la formation des TNTs et sur les m\u00e9canismes de protection des neurones utilisant ces nanotubes. Ils ont observ\u00e9 que certaines mutations sur les g\u00e8nes LRRK2 et Trem2, respectivement li\u00e9es \u00e0 la maladie de Parkinson et \u00e0 la d\u00e9mence fronto-temporale, r\u00e9duisent l&rsquo;\u00e9limination des agr\u00e9gats de prot\u00e9ines toxiques ou compromettent l&rsquo;apport en mitochondries fonctionnelles. Par ailleurs, des alt\u00e9rations li\u00e9es \u00e0 la maladie de Parkinson sur le g\u00e8ne Rac1 pourraient \u00e9galement affecter la formation des nanotubes.<br><br>Ces r\u00e9sultats indiquent de nouveaux m\u00e9canismes par lesquels ces mutations g\u00e9n\u00e9tiques connues contribuent aux maladies neurod\u00e9g\u00e9n\u00e9ratives. En effet, en perturbant le bon fonctionnement des TNTs, elles emp\u00eachent les cellules microgliales de prot\u00e9ger les neurones efficacement. Cibler ces mutations pour am\u00e9liorer la formation de TNTs et activer les transferts via ces nanotubes pourrait donc permettre de freiner la progression de certaines maladies neurod\u00e9g\u00e9n\u00e9ratives.<\/p>\n\n\n\n<h4 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"une-collaboration-internationale-pour-des-resultats-prometteurs\"\n    >\nUne collaboration internationale pour des r\u00e9sultats prometteurs<\/h4>\n\n\n\n<p>Ces travaux de recherche ont \u00e9t\u00e9 men\u00e9 avec plusieurs collaborateurs cl\u00e9s, dont <a href=\"https:\/\/www.dzne.de\/en\/research\/research-areas\/fundamental-research\/research-groups\/bano\/research-areasfocus\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dr Daniele Bano<\/a>, <a href=\"https:\/\/www.dzne.de\/en\/research\/research-areas\/fundamental-research\/research-groups\/di-monte\/research-areasfocus\/\" target=\"_blank\" rel=\"noreferrer noopener\">Prof. Donato Di Monte<\/a> et <a href=\"https:\/\/www.dzne.de\/forschung\/forschungsbereiche\/grundlagenforschung\/forschungsgruppen\/latz\/curriculum-vitae\/\" target=\"_blank\" rel=\"noreferrer noopener\">Prof. Eike Latz<\/a> du German Center for Neurodegenerative Diseases, <a href=\"https:\/\/koki.hun-ren.hu\/researchgroups\/neuroimmunology\" target=\"_blank\" rel=\"noreferrer noopener\">Dr \u00c1d\u00e1m D\u00e9nes<\/a> de l&rsquo;Institute of Experimental Medicine de Budapest, <a href=\"https:\/\/jacob.cea.fr\/drf\/ifrancoisjacob\/english\/Pages\/Departments\/MIRCen\/ResearchThemes\/Protein-misfolding-aggregation-neurodegenerative-diseases.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Dr Ronald Melki<\/a> de l&rsquo;Institut de biologie Fran\u00e7ois Jacob \u00e0 Paris et <a href=\"https:\/\/www.uni-muenster.de\/OCCMuenster\/members\/hans-christian-pape.html\" target=\"_blank\" rel=\"noreferrer noopener\">Prof. Hans-Christian Pape<\/a> de l&rsquo;Universit\u00e9 de M\u00fcnster. Gr\u00e2ce \u00e0 ce travail d&rsquo;\u00e9quipe et aux donn\u00e9es g\u00e9n\u00e9r\u00e9es en commun, les r\u00e9sultats obtenus ouvrent de nouvelles pistes pour une meilleure compr\u00e9hension du cerveau et de ses maladies.<br><br>\u00ab Cette \u00e9tude permet non seulement d&rsquo;approfondir notre compr\u00e9hension de la communication intercellulaire par le biais des nanotubes \u00bb, conclut le professeur Michael Heneka. \u00ab Elle remet aussi en question l\u2019id\u00e9e que les cellules microgliales favorise la neuroinflammation, met en \u00e9vidence un nouveau m\u00e9canisme de neuroprotection et donne un aper\u00e7u de possibles strat\u00e9gies th\u00e9rapeutiques contre les maladies neurod\u00e9g\u00e9n\u00e9ratives li\u00e9es \u00e0 l&rsquo;alpha-synucl\u00e9ine et \u00e0 la prot\u00e9ine tau. \u00bb<\/p>\n\n\n<div class=\"wp-block-unilux-blocks-spacer is-spacer-size-sm\"><\/div>\n\n\n<p>&#8212;<br>R\u00e9f\u00e9rence : H. Scheiblich, F. Eikens, L. Wischhof, S. Opitz, K. Ju\u0308ngling, C. Cser\u00e9p, S. V. Schmidt, J. Lambertz, T. Bellande, B. P\u00f3sfai, C. Geck, J. Spitzer, A. Odainic, S. Castro-Gomez, S. Schwartz, I. Boussaad, R. Kru\u0308ger, E. Glaab, D. A. Di Monte, D. Bano, \u00c1. D\u00e9nes, E. Latz, R. Melki, H-C. Pape &amp; M. T. Heneka, <strong><a href=\"https:\/\/www.cell.com\/neuron\/fulltext\/S0896-6273(24)00491-4\" target=\"_blank\" rel=\"noreferrer noopener\">Microglia rescue neurons from aggregate-induced neuronal dysfunction and death through tunneling nanotubes<\/a><\/strong>, <em>Neuron<\/em>, 25 July 2024.<br><br><sub>Image du haut cr\u00e9\u00e9e avec BioRender.com<\/sub><\/p>\n\n\n<div class=\"py-48 first:pt-0 last:pb-0 wp-block-unilux-blocks-people-list\">\n    \n<h2 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"en-savoir-plus-sur-le-chercheur\"\n    >\nEn savoir plus sur le chercheur<\/h2>\n<ul class=\"flex flex-wrap -mx-16 wp-block-unilux-blocks-people-item-wrapper\">\n    <li class=\"w-full md:w-1\/2 p-16 wp-block-unilux-blocks-people-item-automated\"><div class=\"ulux-card card-people bg-theme\"><div class=\"list-people bg-theme\">\n    <div class=\"list-people__container\">\n        <div class=\"list-people__visual\">\n            <figure class=\"wp-block-dev4-reusable-blocks-image\">\n                <!-- Template Image Component: default -->\n<img decoding=\"async\" class=\"w-full\" width=\"\" height=\"\" rel=\"\" alt=\"Prof Michael HENEKA\" src=\"https:\/\/www.uni.lu\/en\/person-image\/NTAwNDQ0MTJfX01pY2hhZWwgSEVORUtB\" srcset=\"https:\/\/www.uni.lu\/en\/person-image\/NTAwNDQ0MTJfX01pY2hhZWwgSEVORUtB--thumbnail 150w,https:\/\/www.uni.lu\/en\/person-image\/NTAwNDQ0MTJfX01pY2hhZWwgSEVORUtB--medium 300w,https:\/\/www.uni.lu\/en\/person-image\/NTAwNDQ0MTJfX01pY2hhZWwgSEVORUtB--medium_large 768w,https:\/\/www.uni.lu\/en\/person-image\/NTAwNDQ0MTJfX01pY2hhZWwgSEVORUtB--large 1024w,https:\/\/www.uni.lu\/en\/person-image\/NTAwNDQ0MTJfX01pY2hhZWwgSEVORUtB--1536x1536 1536w,https:\/\/www.uni.lu\/en\/person-image\/NTAwNDQ0MTJfX01pY2hhZWwgSEVORUtB--2048x2048 2048w\" loading=\"lazy\" \/><!-- end Image Component -->\n            <\/figure>\n        <\/div>\n        <div class=\"list-people__body\">\n            <h3 class=\"list-people__title\">Prof Michael HENEKA<\/h3>\n            <p class=\"list-people__description\">Director of the &quot;Luxembourg Centre for Systems Biomedicine&quot;<\/p>\n            <div class=\"wp-block-unilux-blocks-simple-cta wp-block-unilux-blocks-people-item-automated\">\n    <a\n        href=\"https:\/\/www.uni.lu\/lcsb-en\/people\/michael-heneka\/\"\n        title=\"Prof Michael HENEKA\"\n        class=\"link-text link-text--icon list-people__link link-absolute\"\n        target=\"_blank\"\n    >\n        <span class=\"link-text__body\">\n            <span class=\"link-text__name\">Voir le profil<\/span>\n        <\/span>\n        <svg aria-hidden=\"true\" focusable=\"false\" class=\"icon icon-outline icon--arrow-right \"><use xlink:href=\"https:\/\/www.uni.lu\/wp-content\/themes\/unilux-theme\/assets\/images\/icons\/icons-outline.svg#icon--arrow-right\"><\/use><\/svg>    <\/a>\n<\/div>\n        <\/div>\n    <\/div>\n<\/div>\n<\/div><\/li><\/ul>\n\n<\/div>\n\n\n\n<section class=\"section section wp-block-unilux-blocks-quick-link-discover-section\">\n    <div class=\"container xl:max-w-screen-xl\">\n        \n<h2 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"a-decouvrir\"\n    >\n\u00c0 d\u00e9couvrir<\/h2>\n\n<ul class=\"wp-block-unilux-blocks-quick-link-discover quick-link-list\">\n<li class=\"wp-block-unilux-blocks-quick-link-discover-item\">\n    <a\n                    href=\"https:\/\/www.uni.lu\/lcsb-en\/research-groups\/neuroinflammation\/\"\n                    class=\"quick-link\"\n            target=\"_blank\"\n    >\n            <span class=\"quick-link__container\">\n                <span class=\"quick-link__text\">\n                    \u00c9quipe Neuroinflammation au LCSB                <\/span>\n                <svg aria-hidden=\"true\" focusable=\"false\" class=\"icon icon-outline icon--external-link \"><use xlink:href=\"https:\/\/www.uni.lu\/wp-content\/themes\/unilux-theme\/assets\/images\/icons\/icons-outline.svg#icon--external-link\"><\/use><\/svg>            <\/span>\n    <\/a>\n<\/li>\n\n\n\n<li class=\"wp-block-unilux-blocks-quick-link-discover-item\">\n    <a\n                    href=\"https:\/\/www.uni.lu\/lcsb-en\/events\/30th-european-cell-death-organization-conference\/\"\n                    class=\"quick-link\"\n            target=\"_blank\"\n    >\n            <span class=\"quick-link__container\">\n                <span class=\"quick-link__text\">\n                    European Cell Death Conference                <\/span>\n                <svg aria-hidden=\"true\" focusable=\"false\" class=\"icon icon-outline icon--external-link \"><use xlink:href=\"https:\/\/www.uni.lu\/wp-content\/themes\/unilux-theme\/assets\/images\/icons\/icons-outline.svg#icon--external-link\"><\/use><\/svg>            <\/span>\n    <\/a>\n<\/li>\n\n\n\n<li class=\"wp-block-unilux-blocks-quick-link-discover-item\">\n    <a\n                    href=\"https:\/\/www.uni.lu\/lcsb-fr\/news\/fnr-pearl-chair-on-alzheimers-disease-for-prof-michael-heneka\/\"\n                    class=\"quick-link\"\n            target=\"_blank\"\n    >\n            <span class=\"quick-link__container\">\n                <span class=\"quick-link__text\">\n                    FNR PEARL Chair pour la maladie d&rsquo;Alzheimer                <\/span>\n                <svg aria-hidden=\"true\" focusable=\"false\" class=\"icon icon-outline icon--external-link \"><use xlink:href=\"https:\/\/www.uni.lu\/wp-content\/themes\/unilux-theme\/assets\/images\/icons\/icons-outline.svg#icon--external-link\"><\/use><\/svg>            <\/span>\n    <\/a>\n<\/li>\n<\/ul>\n    <\/div>\n<\/section><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":55,"featured_media":1168,"template":"","format":"standard","meta":{"featured_image_focal_point":[],"show_featured_caption":false,"ulux_newsletter_groups":"","uluxPostTitle":"","uluxPrePostTitle":"","_trash_the_other_posts":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false},"news-category":[3],"news-topic":[18],"organisation":[525,546],"authorship":[55],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Des passerelles entre les cellules pour un cerveau en bonne sant\u00e9 - Universit\u00e9 du Luxembourg I Uni.lu<\/title>\n<meta name=\"description\" content=\"Une \u00e9tude r\u00e9cente montre que les cellules microgliales utilisent des nanotubes pour \u00e9liminer les prot\u00e9ines toxiques qui s\u2019accumulent \u00e0 l\u2019int\u00e9rieur des neurones, contribuant ainsi \u00e0 am\u00e9liorer leur sant\u00e9. Ce m\u00e9canisme pourrait jouer un r\u00f4le essentiel dans la lutte contre la neurod\u00e9g\u00e9n\u00e9rescence.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des passerelles entre les cellules pour un cerveau en bonne sant\u00e9\" \/>\n<meta property=\"og:description\" content=\"Le cerveau contient de nombreux types de cellules, des neurones dont nous avons tous entendu parler aux cellules microgliales, moins connues du grand\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/\" \/>\n<meta property=\"og:site_name\" content=\"LCSB FR\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-06T09:24:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2024\/07\/Illustration_Microglia_Neuron_TNT_FR_V3-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1654\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/\"},\"author\":{\"name\":\"ldebroux\",\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/#\/schema\/person\/72c768c0824714cc3fb524eab4e8a04a\"},\"headline\":\"Des passerelles entre les cellules pour un cerveau en bonne sant\u00e9\",\"datePublished\":\"2024-07-25T15:03:50+00:00\",\"dateModified\":\"2024-11-06T09:24:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/\"},\"wordCount\":1329,\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2024\/07\/Illustration_Microglia_Neuron_TNT_FR_V3-scaled.jpg\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/\",\"url\":\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/\",\"name\":\"Des passerelles entre les cellules pour un cerveau en bonne sant\u00e9 - Universit\u00e9 du Luxembourg I Uni.lu\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2024\/07\/Illustration_Microglia_Neuron_TNT_FR_V3-scaled.jpg\",\"datePublished\":\"2024-07-25T15:03:50+00:00\",\"dateModified\":\"2024-11-06T09:24:10+00:00\",\"description\":\"Une \u00e9tude r\u00e9cente montre que les cellules microgliales utilisent des nanotubes pour \u00e9liminer les prot\u00e9ines toxiques qui s\u2019accumulent \u00e0 l\u2019int\u00e9rieur des neurones, contribuant ainsi \u00e0 am\u00e9liorer leur sant\u00e9. Ce m\u00e9canisme pourrait jouer un r\u00f4le essentiel dans la lutte contre la neurod\u00e9g\u00e9n\u00e9rescence.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#primaryimage\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2024\/07\/Illustration_Microglia_Neuron_TNT_FR_V3-scaled.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2024\/07\/Illustration_Microglia_Neuron_TNT_FR_V3-scaled.jpg\",\"width\":2560,\"height\":1654,\"caption\":\"Neurone, nanotube \u00e0 effet tunnel, et cellule microgliale: Les cellules microgliales prot\u00e8gent les neurones gr\u00e2ce aux nanotubes \u00e0 effet tunnel; Trasfert de mitochondrie saines; \u00c9limination des agr\u00e9gats de prot\u00e9ines toxiques.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uni.lu\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luxembourg Centre for Systems Biomedicine (LCSB)\",\"item\":\"https:\/\/www.uni.lu\/lcsb-fr\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"News\",\"item\":\"https:\/\/www.uni.lu\/lcsb-fr\/news\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Des passerelles entre les cellules pour un cerveau en bonne sant\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/#website\",\"url\":\"https:\/\/www.uni.lu\/lcsb-fr\/\",\"name\":\"LCSB\",\"description\":\"Luxembourg Centre for Systems Biomedicine I Uni.lu\",\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/#organization\"},\"alternateName\":\"Luxembourg Centre for Systems Biomedicine I Universit\u00e9 du Luxembourg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uni.lu\/lcsb-fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/#organization\",\"name\":\"LCSB - Universit\u00e9 du Luxembourg I Uni.lu\",\"alternateName\":\"Luxembourg Centre for Systems Biomedicine\",\"url\":\"https:\/\/www.uni.lu\/lcsb-fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2026\/03\/03113045\/LCSB_SM-Profile_1600x1600px-scaled.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2026\/03\/03113045\/LCSB_SM-Profile_1600x1600px-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"LCSB - Universit\u00e9 du Luxembourg I Uni.lu\"},\"image\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2026\/04\/24144333\/20200609-Belval-Campus_Henri-Goergen-23.jpg\",\"sameAs\":[\"https:\/\/www.linkedin.com\/showcase\/lcsb-university-of-luxembourg\"],\"email\":\"communication@uni.lu\",\"telephone\":\"+3524666441\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"7, avenue des Hauts- Fourneaux\",\"addressLocality\":\"Esch-sur-Alzette\",\"postalCode\":\"4365\",\"addressCountry\":\"LU\"},\"description\":\"Luxembourg Centre for Systems Biomedicine I Uni.lu\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/#\/schema\/person\/72c768c0824714cc3fb524eab4e8a04a\",\"name\":\"ldebroux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/lcsb-fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1fe72a4d30ad89ce11d430c0e5457698?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1fe72a4d30ad89ce11d430c0e5457698?s=96&d=mm&r=g\",\"caption\":\"ldebroux\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Des passerelles entre les cellules pour un cerveau en bonne sant\u00e9 - Universit\u00e9 du Luxembourg I Uni.lu","description":"Une \u00e9tude r\u00e9cente montre que les cellules microgliales utilisent des nanotubes pour \u00e9liminer les prot\u00e9ines toxiques qui s\u2019accumulent \u00e0 l\u2019int\u00e9rieur des neurones, contribuant ainsi \u00e0 am\u00e9liorer leur sant\u00e9. Ce m\u00e9canisme pourrait jouer un r\u00f4le essentiel dans la lutte contre la neurod\u00e9g\u00e9n\u00e9rescence.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/","og_locale":"fr_FR","og_type":"article","og_title":"Des passerelles entre les cellules pour un cerveau en bonne sant\u00e9","og_description":"Le cerveau contient de nombreux types de cellules, des neurones dont nous avons tous entendu parler aux cellules microgliales, moins connues du grand","og_url":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/","og_site_name":"LCSB FR","article_modified_time":"2024-11-06T09:24:10+00:00","og_image":[{"width":2560,"height":1654,"url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2024\/07\/Illustration_Microglia_Neuron_TNT_FR_V3-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#article","isPartOf":{"@id":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/"},"author":{"name":"ldebroux","@id":"https:\/\/www.uni.lu\/lcsb-fr\/#\/schema\/person\/72c768c0824714cc3fb524eab4e8a04a"},"headline":"Des passerelles entre les cellules pour un cerveau en bonne sant\u00e9","datePublished":"2024-07-25T15:03:50+00:00","dateModified":"2024-11-06T09:24:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/"},"wordCount":1329,"publisher":{"@id":"https:\/\/www.uni.lu\/lcsb-fr\/#organization"},"image":{"@id":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2024\/07\/Illustration_Microglia_Neuron_TNT_FR_V3-scaled.jpg","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/","url":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/","name":"Des passerelles entre les cellules pour un cerveau en bonne sant\u00e9 - Universit\u00e9 du Luxembourg I Uni.lu","isPartOf":{"@id":"https:\/\/www.uni.lu\/lcsb-fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#primaryimage"},"image":{"@id":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2024\/07\/Illustration_Microglia_Neuron_TNT_FR_V3-scaled.jpg","datePublished":"2024-07-25T15:03:50+00:00","dateModified":"2024-11-06T09:24:10+00:00","description":"Une \u00e9tude r\u00e9cente montre que les cellules microgliales utilisent des nanotubes pour \u00e9liminer les prot\u00e9ines toxiques qui s\u2019accumulent \u00e0 l\u2019int\u00e9rieur des neurones, contribuant ainsi \u00e0 am\u00e9liorer leur sant\u00e9. Ce m\u00e9canisme pourrait jouer un r\u00f4le essentiel dans la lutte contre la neurod\u00e9g\u00e9n\u00e9rescence.","breadcrumb":{"@id":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#primaryimage","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2024\/07\/Illustration_Microglia_Neuron_TNT_FR_V3-scaled.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2024\/07\/Illustration_Microglia_Neuron_TNT_FR_V3-scaled.jpg","width":2560,"height":1654,"caption":"Neurone, nanotube \u00e0 effet tunnel, et cellule microgliale: Les cellules microgliales prot\u00e8gent les neurones gr\u00e2ce aux nanotubes \u00e0 effet tunnel; Trasfert de mitochondrie saines; \u00c9limination des agr\u00e9gats de prot\u00e9ines toxiques."},{"@type":"BreadcrumbList","@id":"https:\/\/www.uni.lu\/lcsb-fr\/news\/passerelles-entre-cellules-pour-cerveau-en-bonne-sante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uni.lu\/fr"},{"@type":"ListItem","position":2,"name":"Luxembourg Centre for Systems Biomedicine (LCSB)","item":"https:\/\/www.uni.lu\/lcsb-fr\/"},{"@type":"ListItem","position":3,"name":"News","item":"https:\/\/www.uni.lu\/lcsb-fr\/news\/"},{"@type":"ListItem","position":4,"name":"Des passerelles entre les cellules pour un cerveau en bonne sant\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.uni.lu\/lcsb-fr\/#website","url":"https:\/\/www.uni.lu\/lcsb-fr\/","name":"LCSB","description":"Luxembourg Centre for Systems Biomedicine I Uni.lu","publisher":{"@id":"https:\/\/www.uni.lu\/lcsb-fr\/#organization"},"alternateName":"Luxembourg Centre for Systems Biomedicine I Universit\u00e9 du Luxembourg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uni.lu\/lcsb-fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.uni.lu\/lcsb-fr\/#organization","name":"LCSB - Universit\u00e9 du Luxembourg I Uni.lu","alternateName":"Luxembourg Centre for Systems Biomedicine","url":"https:\/\/www.uni.lu\/lcsb-fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/lcsb-fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2026\/03\/03113045\/LCSB_SM-Profile_1600x1600px-scaled.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2026\/03\/03113045\/LCSB_SM-Profile_1600x1600px-scaled.jpg","width":2560,"height":2560,"caption":"LCSB - Universit\u00e9 du Luxembourg I Uni.lu"},"image":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/22\/2026\/04\/24144333\/20200609-Belval-Campus_Henri-Goergen-23.jpg","sameAs":["https:\/\/www.linkedin.com\/showcase\/lcsb-university-of-luxembourg"],"email":"communication@uni.lu","telephone":"+3524666441","address":{"@type":"PostalAddress","streetAddress":"7, avenue des Hauts- Fourneaux","addressLocality":"Esch-sur-Alzette","postalCode":"4365","addressCountry":"LU"},"description":"Luxembourg Centre for Systems Biomedicine I Uni.lu"},{"@type":"Person","@id":"https:\/\/www.uni.lu\/lcsb-fr\/#\/schema\/person\/72c768c0824714cc3fb524eab4e8a04a","name":"ldebroux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/lcsb-fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1fe72a4d30ad89ce11d430c0e5457698?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1fe72a4d30ad89ce11d430c0e5457698?s=96&d=mm&r=g","caption":"ldebroux"}}]}},"blog_id":22,"_links":{"self":[{"href":"https:\/\/www.uni.lu\/lcsb-fr\/wp-json\/wp\/v2\/news\/1161"}],"collection":[{"href":"https:\/\/www.uni.lu\/lcsb-fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.uni.lu\/lcsb-fr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/lcsb-fr\/wp-json\/wp\/v2\/users\/55"}],"version-history":[{"count":4,"href":"https:\/\/www.uni.lu\/lcsb-fr\/wp-json\/wp\/v2\/news\/1161\/revisions"}],"predecessor-version":[{"id":1282,"href":"https:\/\/www.uni.lu\/lcsb-fr\/wp-json\/wp\/v2\/news\/1161\/revisions\/1282"}],"wp:authorship":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/lcsb-fr\/wp-json\/wp\/v2\/users\/55"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/lcsb-fr\/wp-json\/wp\/v2\/media\/1168"}],"wp:attachment":[{"href":"https:\/\/www.uni.lu\/lcsb-fr\/wp-json\/wp\/v2\/media?parent=1161"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/www.uni.lu\/lcsb-fr\/wp-json\/wp\/v2\/news-category?post=1161"},{"taxonomy":"news-topic","embeddable":true,"href":"https:\/\/www.uni.lu\/lcsb-fr\/wp-json\/wp\/v2\/news-topic?post=1161"},{"taxonomy":"organisation","embeddable":true,"href":"https:\/\/www.uni.lu\/lcsb-fr\/wp-json\/wp\/v2\/organisation?post=1161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}