{"id":844,"date":"2023-06-16T12:53:34","date_gmt":"2023-06-16T12:53:34","guid":{"rendered":"https:\/\/website.prod.unilu.spikeseed.cloud\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/"},"modified":"2024-05-08T14:37:54","modified_gmt":"2024-05-08T12:37:54","slug":"les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent","status":"publish","type":"news","link":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/","title":{"rendered":"Les statistiques au service de la sant\u00e9: les professionnels en parlent"},"content":{"rendered":"\n<section class=\"wp-block-unilux-blocks-free-section section\"><div class=\"container xl:max-w-screen-xl\">\n<p>Le 9 juin 2023, l\u2019Universit\u00e9 du Luxembourg et l\u2019Association Nationale des Infirmi\u00e8res et Infirmiers du Luxembourg (ANIL) ont organis\u00e9 une conf\u00e9rence sur l\u2019importance de la culture des donn\u00e9es dans le domaine des soins de sant\u00e9 avec la mise en lumi\u00e8re des travaux r\u00e9alis\u00e9s par Florence Nightingale, math\u00e9maticienne et infirmi\u00e8re pionni\u00e8re reconnue mondialement pour ses travaux.<\/p>\n\n\n\n<p>R\u00e9unissant plus de 80 personnes sur le campus de Belval, la conf\u00e9rence a tout d\u2019abord d\u00e9but\u00e9 par une allocution de <a href=\"https:\/\/www.manghini.info\/about\" target=\"_blank\" title=\"\" rel=\"noopener\">Pierre Mangers<\/a>, CEO de Manghini Consulting, qui a eu l\u2019id\u00e9e pour la conf\u00e9rence, suivie par une allocution de <a href=\"https:\/\/wwwfr.uni.lu\/recherche\/simone_niclou\" target=\"_self\" title=\"\" rel=\"noopener\">Prof. Simone Niclou<\/a>, Vice-rectrice recherche, qui a f\u00e9licit\u00e9 cette initiative et remerci\u00e9 toutes les parties prenantes impliqu\u00e9es dans la cr\u00e9ation des nouveaux Bachelors en Sciences Infirmi\u00e8res \u00e0 l\u2019Universit\u00e9 du Luxembourg.<\/p>\n\n\n\n<p><a href=\"https:\/\/wwwfr.uni.lu\/recherche\/fhse\/lucet\/people2\/ann_kiefer\" target=\"_self\" title=\"\" rel=\"noopener\">Ann Kiefer<\/a>, chercheure postdoctorale au Luxembourg Centre for Educational Testing (LUCET), a pr\u00e9sent\u00e9 l\u2019incroyable parcours de <strong>Florence Nightingale<\/strong> qui, en tant qu\u2019infirmi\u00e8re dans l\u2019arm\u00e9e lors de la guerre de Crim\u00e9e en 1853, a non seulement r\u00e9volutionn\u00e9 les soins infirmiers mais \u00e9galement d\u00e9velopp\u00e9 les statistiques \u00e0 l\u2019aide de repr\u00e9sentations visuelles. Afin d\u2019identifier les causes saisonni\u00e8res de mortalit\u00e9 au sein de l\u2019h\u00f4pital militaire, elle a su r\u00e9colter les bonnes donn\u00e9es, interpr\u00e9ter et choisir la bonne visualisation. En 1858, elle fut la premi\u00e8re femme \u00e0 \u00eatre \u00e9lue membre de la Royal Statistical Society, et devint par la suite membre honoraire de l&rsquo;American Statistical Association. Ainsi, la statistique et les soins infirmiers ont toujours \u00e9t\u00e9 \u00e9troitement li\u00e9s.<\/p>\n\n\n\n<p>Ensuite, <a href=\"https:\/\/www.chl.lu\/fr\/madame-jacqmin-nadine\" target=\"_blank\" title=\"\" rel=\"noopener\">Nadine Jacqmin<\/a>, attach\u00e9e \u00e0 la Direction des soins et responsable de l&rsquo;enseignement au Centre Hospitalier du Luxembourg (CHL), ainsi qu&rsquo;<a href=\"https:\/\/www.linkedin.com\/in\/annemariehanff\/?originalSubdomain=lu\" target=\"_blank\" title=\"\" rel=\"noopener\">Anne-Marie Hanff<\/a>, pr\u00e9sidente de l&rsquo;ANIL, ont expos\u00e9 l&rsquo;int\u00e9gration des r\u00e9sultats de la recherche dans la pratique, dans le cadre des interventions non m\u00e9dicamenteuses de lutte contre la douleur. Les deux infirmi\u00e8res scientifiques ont attir\u00e9 l&rsquo;attention du public sur l&rsquo;importance de l&rsquo;examen critique des \u00e9tudes, la d\u00e9cision clinique de l\u2019infirmi\u00e8re\/l\u2019infimier et de la contextualisation.<\/p>\n\n\n\n<p><a href=\"https:\/\/wwwfr.uni.lu\/recherche\/fstm\/dmath\/people\/christophe_ley\" target=\"_self\" title=\"\" rel=\"noopener\">Christophe Ley<\/a>, professeur de statistiques appliqu\u00e9es \u00e0 l\u2019Universit\u00e9 du Luxembourg, a ensuite abord\u00e9 les bases des statistiques d\u2019une mani\u00e8re tr\u00e8s ludique afin de bien comprendre les r\u00e9sultats de la recherche et l\u2019importance des connaissances de base dans la lecture critique des chiffres et graphiques par les professionnels de sant\u00e9. Il a par exemple expliqu\u00e9 la diff\u00e9rence entre moyenne et m\u00e9diane ainsi qu\u2019entre corr\u00e9lation et causalit\u00e9.<\/p>\n\n\n\n<p>Les nouveaux <a href=\"https:\/\/nursing.uni.lu\/\" target=\"_self\" title=\"\" rel=\"noopener\">Bachelors sp\u00e9cialis\u00e9s en Sciences Infirmi\u00e8res<\/a> ont \u00e9t\u00e9 pr\u00e9sent\u00e9s par <a href=\"https:\/\/wwwfr.uni.lu\/recherche\/fstm\/dlsm\/people\/marie_friedel\" target=\"_self\" title=\"\" rel=\"noopener\">Prof. Marie Friedel<\/a>, co-directrice d\u2019\u00e9tudes de ces nouveaux programmes qui commenceront en septembre 2023 pour des professionnels d\u00e9j\u00e0 dipl\u00f4m\u00e9s en soins infirmiers g\u00e9n\u00e9raux et qui souhaitent se sp\u00e9cialiser en technique m\u00e9dical de chirurgie, anesth\u00e9sie et r\u00e9animation, p\u00e9diatrie ou psychiatrie.<\/p>\n\n\n\n<p>Une table ronde mod\u00e9r\u00e9e par <a href=\"https:\/\/www.linkedin.com\/in\/annick-goerens-426882a6\/?originalSubdomain=lu\" target=\"_blank\" title=\"\" rel=\"noopener\">Annick Goerens<\/a>, journaliste et pr\u00e9sentatrice \u00e0 RTL, a permis d\u2019\u00e9changer sur l\u2019apport de la culture des donn\u00e9es dans les soins de sant\u00e9. Le panel \u00e9tait compos\u00e9 de <a href=\"https:\/\/researchportal.lih.lu\/en\/persons\/gwena%C3%ABlle-le-coroller\" target=\"_blank\" title=\"\" rel=\"noopener\">Gwena\u00eblle Le Coroller<\/a>, Biostatisticienne au Luxembourg Institute of Health (LIH)&nbsp;; <a href=\"https:\/\/wwwfr.uni.lu\/recherche\/fstm\/dlsm\/people\/laurence_bernard\" target=\"_self\" title=\"\" rel=\"noopener\">Laurence Bernard<\/a>, Professeure en sciences infirmi\u00e8res \u00e0 l\u2019Universit\u00e9 du Luxembourg,&nbsp;<a href=\"https:\/\/www.linkedin.com\/in\/castor-aguilera-9942279b\/?originalSubdomain=lu\" target=\"_blank\" title=\"\" rel=\"noopener\">Castor Aguilera<\/a>, Directeur des Soins au sein de la Croix Rouge Luxembourg&nbsp;et Thierry Lentz, repr\u00e9sentant du Cercle des Associations de Patients (CAPAT).<\/p>\n\n\n\n<p>En parall\u00e8le de la conf\u00e9rence et afin de rendre visible les projets qui font progresser les soins de sant\u00e9 au Luxembourg, des posters ont \u00e9t\u00e9 pr\u00e9sent\u00e9s, portant sur un projet professionnel ou une recherche en lien avec les soins de sant\u00e9.<\/p>\n\n\n\n<p>Un cocktail dinatoire a permis de finir agr\u00e9ablement la soir\u00e9e dans un cadre convivial et informel.<\/p>\n\n\n\n<p>L&rsquo;\u00e9v\u00e8nement a re\u00e7u le soutien du projet \u00ab\u00a0ERA Chair in Mathematical Statistics and Data Science \u2013 SanDAL\u00a0\u00bb et du Gender committee de l&rsquo;Universit\u00e9 du Luxembourg.<\/p>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>Le 9 juin 2023, l\u2019Universit\u00e9 du Luxembourg et l\u2019Association Nationale des Infirmi\u00e8res et Infirmiers du Luxembourg (ANIL) ont organis\u00e9 une conf\u00e9rence sur l\u2019importance de la culture des donn\u00e9es dans le domaine des soins de sant\u00e9 avec la mise en lumi\u00e8re des travaux r\u00e9alis\u00e9s par Florence Nightingale, math\u00e9maticienne et infirmi\u00e8re pionni\u00e8re reconnue mondialement pour ses travaux.<\/p>\n","protected":false},"author":51,"featured_media":2510,"template":"","format":"standard","meta":{"featured_image_focal_point":[],"show_featured_caption":false,"ulux_newsletter_groups":"","uluxPostTitle":"","uluxPrePostTitle":"","_trash_the_other_posts":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false},"news-category":[3],"news-topic":[19,18],"organisation":[95,60,24],"authorship":[51],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les statistiques au service de la sant\u00e9: les professionnels en parlent - FSTM actualit\u00e9s I Universit\u00e9 du Luxembourg<\/title>\n<meta name=\"description\" content=\"Le 9 juin 2023, l\u2019Universit\u00e9 du Luxembourg et l\u2019Association Nationale des Infirmi\u00e8res et Infirmiers du Luxembourg (ANIL) ont organis\u00e9 une conf\u00e9rence sur l\u2019importance de la culture des donn\u00e9es dans le domaine des soins de sant\u00e9 avec la mise en lumi\u00e8re des travaux r\u00e9alis\u00e9s par Florence Nightingale, math\u00e9maticienne et infirmi\u00e8re pionni\u00e8re reconnue mondialement pour ses travaux.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les statistiques au service de la sant\u00e9: les professionnels en parlent\" \/>\n<meta property=\"og:description\" content=\"Le 9 juin 2023, l\u2019Universit\u00e9 du Luxembourg et l\u2019Association Nationale des Infirmi\u00e8res et Infirmiers du Luxembourg (ANIL) ont organis\u00e9 une conf\u00e9rence sur l\u2019importance de la culture des donn\u00e9es dans le domaine des soins de sant\u00e9 avec la mise en lumi\u00e8re des travaux r\u00e9alis\u00e9s par Florence Nightingale, math\u00e9maticienne et infirmi\u00e8re pionni\u00e8re reconnue mondialement pour ses travaux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/\" \/>\n<meta property=\"og:site_name\" content=\"FSTM FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fstm.uni.lu\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-08T12:37:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2023\/06\/IMG_9165-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/\"},\"author\":{\"name\":\"acouvidat\",\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/#\/schema\/person\/35afc7d20f18bad3b124c529eaa7629c\"},\"headline\":\"Les statistiques au service de la sant\u00e9: les professionnels en parlent\",\"datePublished\":\"2023-06-16T12:53:34+00:00\",\"dateModified\":\"2024-05-08T12:37:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/\"},\"wordCount\":691,\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2023\/06\/IMG_9165-scaled.jpg\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/\",\"url\":\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/\",\"name\":\"Les statistiques au service de la sant\u00e9: les professionnels en parlent - FSTM actualit\u00e9s I Universit\u00e9 du Luxembourg\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2023\/06\/IMG_9165-scaled.jpg\",\"datePublished\":\"2023-06-16T12:53:34+00:00\",\"dateModified\":\"2024-05-08T12:37:54+00:00\",\"description\":\"Le 9 juin 2023, l\u2019Universit\u00e9 du Luxembourg et l\u2019Association Nationale des Infirmi\u00e8res et Infirmiers du Luxembourg (ANIL) ont organis\u00e9 une conf\u00e9rence sur l\u2019importance de la culture des donn\u00e9es dans le domaine des soins de sant\u00e9 avec la mise en lumi\u00e8re des travaux r\u00e9alis\u00e9s par Florence Nightingale, math\u00e9maticienne et infirmi\u00e8re pionni\u00e8re reconnue mondialement pour ses travaux.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#primaryimage\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2023\/06\/IMG_9165-scaled.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2023\/06\/IMG_9165-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uni.lu\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facult\u00e9 des Sciences, des Technologies et de M\u00e9decine\",\"item\":\"https:\/\/www.uni.lu\/fstm-fr\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"News\",\"item\":\"https:\/\/www.uni.lu\/fstm-fr\/news\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Les statistiques au service de la sant\u00e9: les professionnels en parlent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/#website\",\"url\":\"https:\/\/www.uni.lu\/fstm-fr\/\",\"name\":\"FSTM\",\"description\":\"Facult\u00e9 des Sciences, des Technologies et de M\u00e9decine I Uni.lu\",\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/#organization\"},\"alternateName\":\"Facult\u00e9 des Sciences, des Technologies et de M\u00e9decine I Universit\u00e9 du Luxembourg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uni.lu\/fstm-fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/#organization\",\"name\":\"FSTM - Universit\u00e9 du Luxembourg I Uni.lu\",\"alternateName\":\"Facult\u00e9 des Sciences, des Technologies et de M\u00e9decine\",\"url\":\"https:\/\/www.uni.lu\/fstm-fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2026\/03\/03111744\/FSTM_SM-Profile_1600x1600px-scaled.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2026\/03\/03111744\/FSTM_SM-Profile_1600x1600px-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"FSTM - Universit\u00e9 du Luxembourg I Uni.lu\"},\"image\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2026\/04\/24144332\/20200609-Belval-Campus_Henri-Goergen-23.jpg\",\"sameAs\":[\"https:\/\/www.facebook.com\/fstm.uni.lu\/\",\"https:\/\/www.linkedin.com\/showcase\/fstm-uni-lu\"],\"email\":\"communication@uni.lu\",\"telephone\":\"+3524666441\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"2, place de l\u2019Universit\u00e9\",\"addressLocality\":\"Esch-sur-Alzette\",\"postalCode\":\"4365\",\"addressCountry\":\"LU\"},\"description\":\"Facult\u00e9 des Sciences, des Technologies et de M\u00e9decine I Uni.lu\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/#\/schema\/person\/35afc7d20f18bad3b124c529eaa7629c\",\"name\":\"acouvidat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/fstm-fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/27deb4989fd3d953fc9d15546b8fe4ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/27deb4989fd3d953fc9d15546b8fe4ee?s=96&d=mm&r=g\",\"caption\":\"acouvidat\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les statistiques au service de la sant\u00e9: les professionnels en parlent - FSTM actualit\u00e9s I Universit\u00e9 du Luxembourg","description":"Le 9 juin 2023, l\u2019Universit\u00e9 du Luxembourg et l\u2019Association Nationale des Infirmi\u00e8res et Infirmiers du Luxembourg (ANIL) ont organis\u00e9 une conf\u00e9rence sur l\u2019importance de la culture des donn\u00e9es dans le domaine des soins de sant\u00e9 avec la mise en lumi\u00e8re des travaux r\u00e9alis\u00e9s par Florence Nightingale, math\u00e9maticienne et infirmi\u00e8re pionni\u00e8re reconnue mondialement pour ses travaux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/","og_locale":"fr_FR","og_type":"article","og_title":"Les statistiques au service de la sant\u00e9: les professionnels en parlent","og_description":"Le 9 juin 2023, l\u2019Universit\u00e9 du Luxembourg et l\u2019Association Nationale des Infirmi\u00e8res et Infirmiers du Luxembourg (ANIL) ont organis\u00e9 une conf\u00e9rence sur l\u2019importance de la culture des donn\u00e9es dans le domaine des soins de sant\u00e9 avec la mise en lumi\u00e8re des travaux r\u00e9alis\u00e9s par Florence Nightingale, math\u00e9maticienne et infirmi\u00e8re pionni\u00e8re reconnue mondialement pour ses travaux.","og_url":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/","og_site_name":"FSTM FR","article_publisher":"https:\/\/www.facebook.com\/fstm.uni.lu\/","article_modified_time":"2024-05-08T12:37:54+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2023\/06\/IMG_9165-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#article","isPartOf":{"@id":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/"},"author":{"name":"acouvidat","@id":"https:\/\/www.uni.lu\/fstm-fr\/#\/schema\/person\/35afc7d20f18bad3b124c529eaa7629c"},"headline":"Les statistiques au service de la sant\u00e9: les professionnels en parlent","datePublished":"2023-06-16T12:53:34+00:00","dateModified":"2024-05-08T12:37:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/"},"wordCount":691,"publisher":{"@id":"https:\/\/www.uni.lu\/fstm-fr\/#organization"},"image":{"@id":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2023\/06\/IMG_9165-scaled.jpg","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/","url":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/","name":"Les statistiques au service de la sant\u00e9: les professionnels en parlent - FSTM actualit\u00e9s I Universit\u00e9 du Luxembourg","isPartOf":{"@id":"https:\/\/www.uni.lu\/fstm-fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#primaryimage"},"image":{"@id":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2023\/06\/IMG_9165-scaled.jpg","datePublished":"2023-06-16T12:53:34+00:00","dateModified":"2024-05-08T12:37:54+00:00","description":"Le 9 juin 2023, l\u2019Universit\u00e9 du Luxembourg et l\u2019Association Nationale des Infirmi\u00e8res et Infirmiers du Luxembourg (ANIL) ont organis\u00e9 une conf\u00e9rence sur l\u2019importance de la culture des donn\u00e9es dans le domaine des soins de sant\u00e9 avec la mise en lumi\u00e8re des travaux r\u00e9alis\u00e9s par Florence Nightingale, math\u00e9maticienne et infirmi\u00e8re pionni\u00e8re reconnue mondialement pour ses travaux.","breadcrumb":{"@id":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#primaryimage","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2023\/06\/IMG_9165-scaled.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2023\/06\/IMG_9165-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.uni.lu\/fstm-fr\/news\/les-statistiques-au-service-de-la-sante-les-professionnels-en-parlent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uni.lu\/fr"},{"@type":"ListItem","position":2,"name":"Facult\u00e9 des Sciences, des Technologies et de M\u00e9decine","item":"https:\/\/www.uni.lu\/fstm-fr\/"},{"@type":"ListItem","position":3,"name":"News","item":"https:\/\/www.uni.lu\/fstm-fr\/news\/"},{"@type":"ListItem","position":4,"name":"Les statistiques au service de la sant\u00e9: les professionnels en parlent"}]},{"@type":"WebSite","@id":"https:\/\/www.uni.lu\/fstm-fr\/#website","url":"https:\/\/www.uni.lu\/fstm-fr\/","name":"FSTM","description":"Facult\u00e9 des Sciences, des Technologies et de M\u00e9decine I Uni.lu","publisher":{"@id":"https:\/\/www.uni.lu\/fstm-fr\/#organization"},"alternateName":"Facult\u00e9 des Sciences, des Technologies et de M\u00e9decine I Universit\u00e9 du Luxembourg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uni.lu\/fstm-fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.uni.lu\/fstm-fr\/#organization","name":"FSTM - Universit\u00e9 du Luxembourg I Uni.lu","alternateName":"Facult\u00e9 des Sciences, des Technologies et de M\u00e9decine","url":"https:\/\/www.uni.lu\/fstm-fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/fstm-fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2026\/03\/03111744\/FSTM_SM-Profile_1600x1600px-scaled.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2026\/03\/03111744\/FSTM_SM-Profile_1600x1600px-scaled.jpg","width":2560,"height":2560,"caption":"FSTM - Universit\u00e9 du Luxembourg I Uni.lu"},"image":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/20\/2026\/04\/24144332\/20200609-Belval-Campus_Henri-Goergen-23.jpg","sameAs":["https:\/\/www.facebook.com\/fstm.uni.lu\/","https:\/\/www.linkedin.com\/showcase\/fstm-uni-lu"],"email":"communication@uni.lu","telephone":"+3524666441","address":{"@type":"PostalAddress","streetAddress":"2, place de l\u2019Universit\u00e9","addressLocality":"Esch-sur-Alzette","postalCode":"4365","addressCountry":"LU"},"description":"Facult\u00e9 des Sciences, des Technologies et de M\u00e9decine I Uni.lu"},{"@type":"Person","@id":"https:\/\/www.uni.lu\/fstm-fr\/#\/schema\/person\/35afc7d20f18bad3b124c529eaa7629c","name":"acouvidat","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/fstm-fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/27deb4989fd3d953fc9d15546b8fe4ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/27deb4989fd3d953fc9d15546b8fe4ee?s=96&d=mm&r=g","caption":"acouvidat"}}]}},"blog_id":20,"_links":{"self":[{"href":"https:\/\/www.uni.lu\/fstm-fr\/wp-json\/wp\/v2\/news\/844"}],"collection":[{"href":"https:\/\/www.uni.lu\/fstm-fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.uni.lu\/fstm-fr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fstm-fr\/wp-json\/wp\/v2\/users\/51"}],"version-history":[{"count":1,"href":"https:\/\/www.uni.lu\/fstm-fr\/wp-json\/wp\/v2\/news\/844\/revisions"}],"predecessor-version":[{"id":2511,"href":"https:\/\/www.uni.lu\/fstm-fr\/wp-json\/wp\/v2\/news\/844\/revisions\/2511"}],"wp:authorship":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fstm-fr\/wp-json\/wp\/v2\/users\/51"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fstm-fr\/wp-json\/wp\/v2\/media\/2510"}],"wp:attachment":[{"href":"https:\/\/www.uni.lu\/fstm-fr\/wp-json\/wp\/v2\/media?parent=844"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/www.uni.lu\/fstm-fr\/wp-json\/wp\/v2\/news-category?post=844"},{"taxonomy":"news-topic","embeddable":true,"href":"https:\/\/www.uni.lu\/fstm-fr\/wp-json\/wp\/v2\/news-topic?post=844"},{"taxonomy":"organisation","embeddable":true,"href":"https:\/\/www.uni.lu\/fstm-fr\/wp-json\/wp\/v2\/organisation?post=844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}