{"id":2424,"date":"2021-03-10T14:37:00","date_gmt":"2021-03-10T13:37:00","guid":{"rendered":"https:\/\/www.uni.lu\/fr\/?post_type=news&#038;p=2424"},"modified":"2023-11-20T15:57:31","modified_gmt":"2023-11-20T14:57:31","slug":"webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir","status":"publish","type":"news","link":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/","title":{"rendered":"Webinaire: L\u2019Union \u00e9conomique belgo-luxembourgeoise (UEBL) &#8211; Le\u00e7ons du pass\u00e9, perspectives d\u2019avenir"},"content":{"rendered":"\n<section class=\"wp-block-unilux-blocks-free-section section\"><div class=\"container xl:max-w-screen-xl\">\n<p>L\u2019Union \u00e9conomique belgo- luxembourgeoise (UEBL) a \u00e9t\u00e9 conclue le 25 juillet 1921. La Convention y relative est compl\u00e9t\u00e9e en 1935 par un volet financier et mon\u00e9taire, un r\u00e9gime commercial commun et une \u00ab communaut\u00e9 sp\u00e9ciale de recettes \u00bb en mati\u00e8re d\u2019accises sp\u00e9cifiques. En 1963, les dispositions de l\u2019UEBL \u00e9voluent suite \u00e0 l\u2019entr\u00e9e en vigueur de la Communaut\u00e9 \u00e9conomique europ\u00e9enne (CEE) et du Benelux. Souhaitant amplifier leur coop\u00e9ration au-del\u00e0 des domaines \u00e9conomiques et mon\u00e9taires, le 18 d\u00e9cembre 2002, les deux pays renouvellent la Convention sous une forme enrichie, ouvrant ainsi de nouvelles perspectives pour une coop\u00e9ration politique et administrative renforc\u00e9e notamment en mati\u00e8re de justice, de citoyennet\u00e9, de la sant\u00e9 et des synergies transfrontali\u00e8res dans la Grande R\u00e9gion, ainsi que pour la concertation au sein de l\u2019Union europ\u00e9enne. Durant un si\u00e8cle, la Belgique et le Luxembourg ont abouti \u00e0 un partenariat bilat\u00e9ral solide, ponctu\u00e9 de certaines difficult\u00e9s et tensions, mais approfondi et renouvel\u00e9 au fil des ann\u00e9es. Le centenaire de l\u2019UEBL, qui a lieu dans un contexte grand-r\u00e9gional, europ\u00e9en et international \u00e9maill\u00e9 de d\u00e9fis et d\u2019incertitudes sans pr\u00e9c\u00e9dent, invite au d\u00e9bat et \u00e0 la r\u00e9flexion sur les enseignements du pass\u00e9, le bilan actuel et les perspectives d\u2019avenir de cette union.<\/p>\n\n\n\n<p>L\u2019<strong>Europe Direct de l\u2019Universit\u00e9 du Luxembourg (EDIC)<\/strong>&nbsp;et ses partenaires &#8211;&nbsp;le&nbsp;<strong>Centre for Contemporary and Digital History (C\u00b2DH)<\/strong>, le&nbsp;<strong>Luxembourg Institute of Socio-Economic Research (LISER)<\/strong>, le&nbsp;<strong>Minist\u00e8re des Affaires \u00e9trang\u00e8res et europ\u00e9ennes du Grand-Duch\u00e9 du Luxembourg<\/strong>&nbsp;et l\u2019<strong>Ambassade de Belgique au Luxembourg<\/strong>&nbsp;\u2013 ont organis\u00e9 le&nbsp;<strong>mercredi 24 mars 2021 \u00e0 14h00<\/strong>, le webinaire \u00ab&nbsp;<strong>L\u2019Union \u00e9conomique belgo-luxembourgeoise (UEBL) &#8211; Le\u00e7ons du pass\u00e9, perspectives d\u2019avenir<\/strong>&nbsp;\u00bb.<\/p>\n\n\n\n<h2 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"programme\"\n    >\nProgramme<\/h2>\n\n\n\n<h4 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"andre-biever\"\n    >\nAndr\u00e9 Biever<\/h4>\n\n\n\n<p>Andr\u00e9 Biever est titulaire d\u2019un Master en relations internationales de Sciences Po Paris et d\u2019une Ma\u00eetrise d\u2019histoire \u00e0 l\u2019Universit\u00e9 Paris IV-Sorbonne. Il a \u00e9galement travaill\u00e9 \u00e0 la repr\u00e9sentation permanente du Luxembourg aupr\u00e8s des Nations Unies \u00e0 Gen\u00e8ve, mais aussi au sein de la Repr\u00e9sentation permanente du Luxembourg aupr\u00e8s de l\u2019Union Europ\u00e9enne. Il a \u00e9galement travaill\u00e9 au sein des Ambassades du Luxembourg en Inde et au Nicaragua. Depuis le 1er septembre 2019, il est Directeur adjoint au sein de la Direction des affaires europ\u00e9ennes et des relations \u00e9conomiques internationales du Minist\u00e8re des Affaires \u00e9trang\u00e8res et europ\u00e9ennes du Luxembourg.<\/p>\n\n\n\n<h4 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"franz-clement\"\n    >\nFranz Cl\u00e9ment<\/h4>\n\n\n\n<p>Franz Cl\u00e9ment a une formation de base en sciences politiques (Universit\u00e9 catholique de Louvain) et est titulaire d\u2019un dipl\u00f4me d\u2019\u00e9tudes approfondies en sociologie du travail (Universit\u00e9 Nancy 2). Il est \u00e9galement docteur en sociologie dipl\u00f4m\u00e9 du CNAM (Conservatoire national des arts et m\u00e9tiers) \u00e0 Paris. Il exerce son activit\u00e9 professionnelle de chercheur en sciences sociales \u00e0 Esch-Belval au LISER (Luxembourg Institute of Socio Economic Research). Il a produit diverses recherches et publications sur le dialogue social au Luxembourg et dans la Grande R\u00e9gion ainsi que sur les travailleurs frontaliers dans ce m\u00eame espace.<\/p>\n\n\n\n<h4 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"andreas-fickers\"\n    >\nAndreas Fickers<\/h4>\n\n\n\n<p>Andreas Fickers est le directeur du Centre for Contemporary and Digital History (C\u00b2DH) et le chef du DH-Lab. Il a \u00e9tudi\u00e9 l&rsquo;histoire, la philosophie et la sociologie et est actuellement professeur d&rsquo;histoire contemporaine et num\u00e9rique \u00e0 l\u2019Universit\u00e9 du Luxembourg. Il dirige le Doctoral Training Unit \u2018Digital History &amp; Hermeneutics\u2019 (DTU) financ\u00e9 par le FNR et coordonne la Trinational doctoral school. Il est \u00e9galement le chercheur principal des projets DEMA, Popkult60 et LuxTime et \u00e9diteur du Journal of Digital History. Il est actuellement le coordinateur national luxembourgeois de DARIAH-EU et membre du conseil de recherche conjoint Humanities in the European Research Area (HERA).<\/p>\n\n\n\n<h4 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"thomas-lambert\"\n    >\nThomas Lambert<\/h4>\n\n\n\n<p>Thomas Lambert a une formation en droit (Universit\u00e9 Catholique de Leuven et facult\u00e9 de droit de l\u2019Universit\u00e9 d\u2019Aarhus). Apr\u00e8s avoir exerc\u00e9 dans diff\u00e9rents bureaux d\u2019avocats, Thomas Lambert travaille au sein de la Repr\u00e9sentation Permanente de la Belgique aupr\u00e8s des Nations Unies \u00e0 New-York puis aupr\u00e8s de celle de l\u2019Organisation Mondiale pour le Commerce \u00e0 Gen\u00e8ve. En 2004, il exerce la fonction de n\u00e9gociateur f\u00e9d\u00e9ral pour le 7\u00e8me Programme Cadre pour la recherche et l\u2019innovation au sein de la Repr\u00e9sentation Permanente de la Belgique aupr\u00e8s de l\u2019Union Europ\u00e9enne. Il int\u00e8gre, ensuite, le Cabinet du Ministre des Affaires Etrang\u00e8res Belge en tant que Chef de Cabinet Adjoint, puis devient Repr\u00e9sentant Permanent Adjoint au sein de la Repr\u00e9sentation Permanente de la Belgique aupr\u00e8s des Nations-Unies. En 2013, Thomas Lambert est Ambassadeur Suppl\u00e9ant au sein de l\u2019Ambassade de Belgique aupr\u00e8s des Etats-Unis. Depuis septembre 2017, il exerce ses fonctions d\u2019Ambassadeur au sein du Service Public F\u00e9d\u00e9ral des Affaires Etrang\u00e8res \u00e0 Bruxelles.<\/p>\n\n\n\n<h4 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"la-presentation-du-dr-franz-clement-chercheur-au-luxembourg-institute-of-socio-economic-research-liser\"\n    >\nLa pr\u00e9sentation du Dr Franz Cl\u00e9ment, Chercheur au Luxembourg Institute of Socio-Economic Research (LISER)<\/h4>\n\n\n\n<p>Vous pouvez t\u00e9l\u00e9charger la pr\u00e9sentation du Dr Franz Cl\u00e9ment: <a href=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2023\/08\/edic-100-ans-UEBL-conference-EDIC-24-mars-2021.pptx\">Un si\u00e8cle de coop\u00e9ration belgo-luxembourgeoise<\/a><\/p>\n\n\n\n<h4 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"enregistrement-du-webinaire\"\n    >\nEnregistrement du webinaire<\/h4>\n\n\n<div class=\"thumbnail  wp-block-unilux-blocks-thumbnail-video\">\n    <div class=\"card bg-theme p-0\">\n        <div class=\"card__container p-0\">\n            <div class=\"card__body p-0\">\n                <iframe \n            src=\"https:\/\/www.youtube.com\/embed\/6BzlhVyzD6o\" \n            title=\"YouTube video player\" frameborder=\"0\" \n            allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" \n            style=\"object-position: 50% 50%; aspect-ratio: 16\/9; object-fit: cover; width: 100%;\"\n            allowfullscreen data-cookieconsent=\"ignore\">\n            <\/iframe>                            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":45,"featured_media":4540,"template":"","format":"standard","meta":{"featured_image_focal_point":[],"show_featured_caption":false,"ulux_newsletter_groups":"","uluxPostTitle":"","uluxPrePostTitle":"","_trash_the_other_posts":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false},"news-category":[],"news-topic":[],"organisation":[297],"authorship":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Webinaire: L\u2019Union \u00e9conomique belgo-luxembourgeoise (UEBL) - Le\u00e7ons du pass\u00e9, perspectives d\u2019avenir - Universit\u00e9 du Luxembourg<\/title>\n<meta name=\"description\" content=\"L\u2019Union \u00e9conomique belgo- luxembourgeoise (UEBL) a \u00e9t\u00e9 conclue le 25 juillet 1921. La Convention y relative est compl\u00e9t\u00e9e en 1935 par un volet financier\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Webinaire: L\u2019Union \u00e9conomique belgo-luxembourgeoise (UEBL) - Le\u00e7ons du pass\u00e9, perspectives d\u2019avenir\" \/>\n<meta property=\"og:description\" content=\"L\u2019Union \u00e9conomique belgo- luxembourgeoise (UEBL) a \u00e9t\u00e9 conclue le 25 juillet 1921. La Convention y relative est compl\u00e9t\u00e9e en 1935 par un volet financier\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/\" \/>\n<meta property=\"og:site_name\" content=\"UNI FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uni.lu\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-20T14:57:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2023\/11\/Placeholder_news.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/\"},\"author\":{\"name\":\"ltremblet\",\"@id\":\"https:\/\/www.uni.lu\/fr\/#\/schema\/person\/ecb4619186c656deb2b4636b90dd32a8\"},\"headline\":\"Webinaire: L\u2019Union \u00e9conomique belgo-luxembourgeoise (UEBL) &#8211; Le\u00e7ons du pass\u00e9, perspectives d\u2019avenir\",\"datePublished\":\"2021-03-10T13:37:00+00:00\",\"dateModified\":\"2023-11-20T14:57:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/\"},\"wordCount\":834,\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2023\/11\/Placeholder_news.png\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/\",\"url\":\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/\",\"name\":\"Webinaire: L\u2019Union \u00e9conomique belgo-luxembourgeoise (UEBL) - Le\u00e7ons du pass\u00e9, perspectives d\u2019avenir - Universit\u00e9 du Luxembourg\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2023\/11\/Placeholder_news.png\",\"datePublished\":\"2021-03-10T13:37:00+00:00\",\"dateModified\":\"2023-11-20T14:57:31+00:00\",\"description\":\"L\u2019Union \u00e9conomique belgo- luxembourgeoise (UEBL) a \u00e9t\u00e9 conclue le 25 juillet 1921. La Convention y relative est compl\u00e9t\u00e9e en 1935 par un volet financier\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#primaryimage\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2023\/11\/Placeholder_news.png\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2023\/11\/Placeholder_news.png\",\"width\":1500,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uni.lu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/www.uni.lu\/fr\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Webinaire: L\u2019Union \u00e9conomique belgo-luxembourgeoise (UEBL) &#8211; Le\u00e7ons du pass\u00e9, perspectives d\u2019avenir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uni.lu\/fr\/#website\",\"url\":\"https:\/\/www.uni.lu\/fr\/\",\"name\":\"Uni.lu\",\"description\":\"Universit\u00e9 du Luxembourg\",\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/#organization\"},\"alternateName\":\"Universit\u00e9 du Luxembourg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uni.lu\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.uni.lu\/fr\/#organization\",\"name\":\"Universit\u00e9 du Luxembourg\",\"alternateName\":\"Uni.lu\",\"url\":\"https:\/\/www.uni.lu\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2026\/03\/03120045\/UNIV_SM-Profile_1600x1600px-scaled.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2026\/03\/03120045\/UNIV_SM-Profile_1600x1600px-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Universit\u00e9 du Luxembourg\"},\"image\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2026\/04\/24120552\/20200609-Belval-Campus_Henri-Goergen-23.jpg\",\"sameAs\":[\"https:\/\/www.facebook.com\/uni.lu\",\"https:\/\/www.linkedin.com\/school\/university-of-luxembourg\/\",\"https:\/\/www.instagram.com\/uni.lu\",\"https:\/\/www.youtube.com\/@uni_lu\",\"https:\/\/en.wikipedia.org\/wiki\/University_of_Luxembourg\"],\"email\":\"communication@uni.lu\",\"telephone\":\"+352 46 66 44 1\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"2, place de l\u2019Universit\u00e9\",\"addressLocality\":\"Esch-sur-Alzette\",\"postalCode\":\"4365\",\"addressCountry\":\"LU\"},\"description\":\"Universit\u00e9 du Luxembourg\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uni.lu\/fr\/#\/schema\/person\/ecb4619186c656deb2b4636b90dd32a8\",\"name\":\"ltremblet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5c89c001fd28b8a21bc47f29007a543e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5c89c001fd28b8a21bc47f29007a543e?s=96&d=mm&r=g\",\"caption\":\"ltremblet\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Webinaire: L\u2019Union \u00e9conomique belgo-luxembourgeoise (UEBL) - Le\u00e7ons du pass\u00e9, perspectives d\u2019avenir - Universit\u00e9 du Luxembourg","description":"L\u2019Union \u00e9conomique belgo- luxembourgeoise (UEBL) a \u00e9t\u00e9 conclue le 25 juillet 1921. La Convention y relative est compl\u00e9t\u00e9e en 1935 par un volet financier","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/","og_locale":"fr_FR","og_type":"article","og_title":"Webinaire: L\u2019Union \u00e9conomique belgo-luxembourgeoise (UEBL) - Le\u00e7ons du pass\u00e9, perspectives d\u2019avenir","og_description":"L\u2019Union \u00e9conomique belgo- luxembourgeoise (UEBL) a \u00e9t\u00e9 conclue le 25 juillet 1921. La Convention y relative est compl\u00e9t\u00e9e en 1935 par un volet financier","og_url":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/","og_site_name":"UNI FR","article_publisher":"https:\/\/www.facebook.com\/uni.lu","article_modified_time":"2023-11-20T14:57:31+00:00","og_image":[{"width":1500,"height":1125,"url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2023\/11\/Placeholder_news.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#article","isPartOf":{"@id":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/"},"author":{"name":"ltremblet","@id":"https:\/\/www.uni.lu\/fr\/#\/schema\/person\/ecb4619186c656deb2b4636b90dd32a8"},"headline":"Webinaire: L\u2019Union \u00e9conomique belgo-luxembourgeoise (UEBL) &#8211; Le\u00e7ons du pass\u00e9, perspectives d\u2019avenir","datePublished":"2021-03-10T13:37:00+00:00","dateModified":"2023-11-20T14:57:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/"},"wordCount":834,"publisher":{"@id":"https:\/\/www.uni.lu\/fr\/#organization"},"image":{"@id":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2023\/11\/Placeholder_news.png","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/","url":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/","name":"Webinaire: L\u2019Union \u00e9conomique belgo-luxembourgeoise (UEBL) - Le\u00e7ons du pass\u00e9, perspectives d\u2019avenir - Universit\u00e9 du Luxembourg","isPartOf":{"@id":"https:\/\/www.uni.lu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#primaryimage"},"image":{"@id":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2023\/11\/Placeholder_news.png","datePublished":"2021-03-10T13:37:00+00:00","dateModified":"2023-11-20T14:57:31+00:00","description":"L\u2019Union \u00e9conomique belgo- luxembourgeoise (UEBL) a \u00e9t\u00e9 conclue le 25 juillet 1921. La Convention y relative est compl\u00e9t\u00e9e en 1935 par un volet financier","breadcrumb":{"@id":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#primaryimage","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2023\/11\/Placeholder_news.png","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2023\/11\/Placeholder_news.png","width":1500,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/www.uni.lu\/fr\/news\/webinaire-lunion-economique-belgo-luxembourgeoise-uebl-lecons-du-passe-perspectives-davenir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uni.lu\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.uni.lu\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Webinaire: L\u2019Union \u00e9conomique belgo-luxembourgeoise (UEBL) &#8211; Le\u00e7ons du pass\u00e9, perspectives d\u2019avenir"}]},{"@type":"WebSite","@id":"https:\/\/www.uni.lu\/fr\/#website","url":"https:\/\/www.uni.lu\/fr\/","name":"Uni.lu","description":"Universit\u00e9 du Luxembourg","publisher":{"@id":"https:\/\/www.uni.lu\/fr\/#organization"},"alternateName":"Universit\u00e9 du Luxembourg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uni.lu\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.uni.lu\/fr\/#organization","name":"Universit\u00e9 du Luxembourg","alternateName":"Uni.lu","url":"https:\/\/www.uni.lu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2026\/03\/03120045\/UNIV_SM-Profile_1600x1600px-scaled.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2026\/03\/03120045\/UNIV_SM-Profile_1600x1600px-scaled.jpg","width":2560,"height":2560,"caption":"Universit\u00e9 du Luxembourg"},"image":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2026\/04\/24120552\/20200609-Belval-Campus_Henri-Goergen-23.jpg","sameAs":["https:\/\/www.facebook.com\/uni.lu","https:\/\/www.linkedin.com\/school\/university-of-luxembourg\/","https:\/\/www.instagram.com\/uni.lu","https:\/\/www.youtube.com\/@uni_lu","https:\/\/en.wikipedia.org\/wiki\/University_of_Luxembourg"],"email":"communication@uni.lu","telephone":"+352 46 66 44 1","address":{"@type":"PostalAddress","streetAddress":"2, place de l\u2019Universit\u00e9","addressLocality":"Esch-sur-Alzette","postalCode":"4365","addressCountry":"LU"},"description":"Universit\u00e9 du Luxembourg"},{"@type":"Person","@id":"https:\/\/www.uni.lu\/fr\/#\/schema\/person\/ecb4619186c656deb2b4636b90dd32a8","name":"ltremblet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5c89c001fd28b8a21bc47f29007a543e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c89c001fd28b8a21bc47f29007a543e?s=96&d=mm&r=g","caption":"ltremblet"}}]}},"blog_id":11,"_links":{"self":[{"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/news\/2424"}],"collection":[{"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/users\/45"}],"version-history":[{"count":6,"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/news\/2424\/revisions"}],"predecessor-version":[{"id":12607,"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/news\/2424\/revisions\/12607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/media\/4540"}],"wp:attachment":[{"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/media?parent=2424"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/news-category?post=2424"},{"taxonomy":"news-topic","embeddable":true,"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/news-topic?post=2424"},{"taxonomy":"organisation","embeddable":true,"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/organisation?post=2424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}