{"id":1550,"date":"2021-10-25T13:35:15","date_gmt":"2021-10-25T13:35:15","guid":{"rendered":"https:\/\/website.prod.unilu.spikeseed.cloud\/fr\/news\/uni-lu-introduit-des-frais-de-dossier-de-50-eur\/"},"modified":"2021-10-25T13:35:15","modified_gmt":"2021-10-25T13:35:15","slug":"uni-lu-introduit-des-frais-de-dossier-de-50-eur","status":"publish","type":"news","link":"https:\/\/www.uni.lu\/fr\/news\/uni-lu-introduit-des-frais-de-dossier-de-50-eur\/","title":{"rendered":"Uni.lu introduit des frais de dossier de 50 EUR"},"content":{"rendered":"<section class=\"wp-block-unilux-blocks-free-section section\"><div class=\"container xl:max-w-screen-xl\"><p><i>La mesure entrera en vigueur \u00e0 la prochaine p\u00e9riode d\u2019admission en f\u00e9vrier 2022.<\/i><\/p><p>L\u2019Universit\u00e9 du Luxembourg introduira, \u00e0 partir de l\u2019ann\u00e9e acad\u00e9mique 2022-2023, des frais de dossier afin de contribuer \u00e0 l&rsquo;administration des demandes d&rsquo;admission et pour assurer aux candidats une exp\u00e9rience d&rsquo;admission positive.<\/p><p>Les frais de dossier sont fix\u00e9s \u00e0 50 EUR par dossier\u00a0; ils seront factur\u00e9s \u00e0 partir de la prochaine p\u00e9riode d\u2019admission (ouverture des candidatures, f\u00e9vrier 2022) et pour chaque demande d\u2019admission \u00e0 un programme d\u2019\u00e9tudes pour l\u2019ann\u00e9e 2022-23. Les frais de dossier s\u2019appliqueront \u00e0 tous les candidats \u00e9tudiants, quelle que soit leur nationalit\u00e9 ou pays de r\u00e9sidence. Aucun candidat ne peut postuler \u00e0 l\u2019admission dans plus de trois programmes d\u2019\u00e9tudes de l\u2019Universit\u00e9.<\/p>\n<h3 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"remboursement-et-exceptions\"\n    >\nRemboursement et exceptions<\/h3>\n<p>Les \u00e9tudiants dont la candidature sera accept\u00e9e et qui s\u2019inscrivent dans un programme d\u2019\u00e9tudes verront les frais de dossier d\u00e9duits de leurs frais d\u2019inscription au premier semestre. Les frais de dossier ne sont pas remboursables pour des dossiers de candidature qui sont rejet\u00e9s.<\/p><p>Les frais de dossier ne s\u2019appliqueront pas aux \u00e9tudiants qui progressent d\u2019une ann\u00e9e d\u2019\u00e9tudes \u00e0 la suivante \u00e0 l\u2019int\u00e9rieur de leur programme d\u2019\u00e9tudes. Ils ne s\u2019appliqueront pas non plus aux candidats \u00e9tudiants inscrits \u00e0 l\u2019Universit\u00e9, ayant accompli leur programme d\u2019\u00e9tudes avec succ\u00e8s, et qui souhaiteraient poursuivre leurs \u00e9tudes \u00e0 l\u2019Universit\u00e9 du Luxembourg (strictement lors du passage d\u2019un programme bachelor \u00e0 un programme de master).<\/p><p>Les frais de dossier ne s\u2019appliqueront pas non plus aux \u00e9tudes doctorales, ni aux formations compl\u00e9mentaires menant \u00e0 des certificats, ni aux auditeurs libres. Seront \u00e9galement exempts de frais de dossier les \u00e9tudiants ayant int\u00e9gr\u00e9 l\u2019Universit\u00e9 dans le cadre de conventions internationales avec des universit\u00e9s partenaires, ainsi que les \u00e9tudiants en mobilit\u00e9 \u00e0 l\u2019Universit\u00e9 du Luxembourg dans le cadre d\u2019un programme Erasmus.<\/p><p>L\u2019Universit\u00e9 du Luxembourg a introduit une proc\u00e9dure de candidature num\u00e9rique (\u00ab\u00a0paperless\u00a0\u00bb) depuis le printemps 2021. Les frais de dossier se placent dans le contexte de la recherche d\u2019une am\u00e9lioration constante du niveau de service offert.<\/p><p>L\u2019Universit\u00e9 compte actuellement quelque 4 900 \u00e9tudiants inscrits dans ses diff\u00e9rents programmes de Bachelor et Master.<\/p><p>Pour l\u2019ann\u00e9e acad\u00e9mique 2021-2022, l\u2019Universit\u00e9 a re\u00e7u 15 100 demandes d\u2019admission pour ses programmes de Bachelor et Master, dont 11 700 nouvelles candidatures pour une premi\u00e8re inscription.<\/p><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>La mesure entrera en vigueur \u00e0 la prochaine p\u00e9riode d\u2019admission en f\u00e9vrier 2022.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","format":"standard","meta":{"featured_image_focal_point":[],"show_featured_caption":false,"ulux_newsletter_groups":"","uluxPostTitle":"","uluxPrePostTitle":"","_trash_the_other_posts":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false},"news-category":[3],"news-topic":[],"organisation":[226],"authorship":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Uni.lu introduit des frais de dossier de 50 EUR - Universit\u00e9 du Luxembourg<\/title>\n<meta name=\"description\" content=\"La mesure entrera en vigueur \u00e0 la prochaine p\u00e9riode d\u2019admission en f\u00e9vrier 2022.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uni.lu\/fr\/news\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uni.lu introduit des frais de dossier de 50 EUR\" \/>\n<meta property=\"og:description\" content=\"La mesure entrera en vigueur \u00e0 la prochaine p\u00e9riode d\u2019admission en f\u00e9vrier 2022.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uni.lu\/fr\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"UNI FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uni.lu\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2021\/10\/uni_lu_introduit_des_frais_de_dossier_de_50_eur.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Uni.lu introduit des frais de dossier de 50 EUR\",\"datePublished\":\"2021-10-25T13:35:15+00:00\",\"dateModified\":\"2021-10-25T13:35:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/\"},\"wordCount\":412,\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/\",\"url\":\"https:\/\/www.uni.lu\/fr\/news\/\",\"name\":\"Uni.lu introduit des frais de dossier de 50 EUR - Universit\u00e9 du Luxembourg\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/#website\"},\"datePublished\":\"2021-10-25T13:35:15+00:00\",\"dateModified\":\"2021-10-25T13:35:15+00:00\",\"description\":\"La mesure entrera en vigueur \u00e0 la prochaine p\u00e9riode d\u2019admission en f\u00e9vrier 2022.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uni.lu\/fr\/news\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uni.lu\/fr\/news\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uni.lu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/www.uni.lu\/fr\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Uni.lu introduit des frais de dossier de 50 EUR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uni.lu\/fr\/#website\",\"url\":\"https:\/\/www.uni.lu\/fr\/\",\"name\":\"Uni.lu\",\"description\":\"Universit\u00e9 du Luxembourg\",\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/fr\/#organization\"},\"alternateName\":\"Universit\u00e9 du Luxembourg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uni.lu\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.uni.lu\/fr\/#organization\",\"name\":\"Universit\u00e9 du Luxembourg\",\"alternateName\":\"Uni.lu\",\"url\":\"https:\/\/www.uni.lu\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2026\/03\/03120045\/UNIV_SM-Profile_1600x1600px-scaled.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2026\/03\/03120045\/UNIV_SM-Profile_1600x1600px-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Universit\u00e9 du Luxembourg\"},\"image\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2026\/04\/24120552\/20200609-Belval-Campus_Henri-Goergen-23.jpg\",\"sameAs\":[\"https:\/\/www.facebook.com\/uni.lu\",\"https:\/\/www.linkedin.com\/school\/university-of-luxembourg\/\",\"https:\/\/www.instagram.com\/uni.lu\",\"https:\/\/www.youtube.com\/@uni_lu\",\"https:\/\/en.wikipedia.org\/wiki\/University_of_Luxembourg\"],\"email\":\"communication@uni.lu\",\"telephone\":\"+352 46 66 44 1\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"2, place de l\u2019Universit\u00e9\",\"addressLocality\":\"Esch-sur-Alzette\",\"postalCode\":\"4365\",\"addressCountry\":\"LU\"},\"description\":\"Universit\u00e9 du Luxembourg\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Uni.lu introduit des frais de dossier de 50 EUR - Universit\u00e9 du Luxembourg","description":"La mesure entrera en vigueur \u00e0 la prochaine p\u00e9riode d\u2019admission en f\u00e9vrier 2022.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uni.lu\/fr\/news\/","og_locale":"fr_FR","og_type":"article","og_title":"Uni.lu introduit des frais de dossier de 50 EUR","og_description":"La mesure entrera en vigueur \u00e0 la prochaine p\u00e9riode d\u2019admission en f\u00e9vrier 2022.","og_url":"https:\/\/www.uni.lu\/fr\/news\/","og_site_name":"UNI FR","article_publisher":"https:\/\/www.facebook.com\/uni.lu","og_image":[{"width":800,"height":600,"url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2021\/10\/uni_lu_introduit_des_frais_de_dossier_de_50_eur.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.uni.lu\/fr\/news\/#article","isPartOf":{"@id":"https:\/\/www.uni.lu\/fr\/news\/"},"author":{"name":"","@id":""},"headline":"Uni.lu introduit des frais de dossier de 50 EUR","datePublished":"2021-10-25T13:35:15+00:00","dateModified":"2021-10-25T13:35:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uni.lu\/fr\/news\/"},"wordCount":412,"publisher":{"@id":"https:\/\/www.uni.lu\/fr\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.uni.lu\/fr\/news\/","url":"https:\/\/www.uni.lu\/fr\/news\/","name":"Uni.lu introduit des frais de dossier de 50 EUR - Universit\u00e9 du Luxembourg","isPartOf":{"@id":"https:\/\/www.uni.lu\/fr\/#website"},"datePublished":"2021-10-25T13:35:15+00:00","dateModified":"2021-10-25T13:35:15+00:00","description":"La mesure entrera en vigueur \u00e0 la prochaine p\u00e9riode d\u2019admission en f\u00e9vrier 2022.","breadcrumb":{"@id":"https:\/\/www.uni.lu\/fr\/news\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uni.lu\/fr\/news\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.uni.lu\/fr\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uni.lu\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.uni.lu\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Uni.lu introduit des frais de dossier de 50 EUR"}]},{"@type":"WebSite","@id":"https:\/\/www.uni.lu\/fr\/#website","url":"https:\/\/www.uni.lu\/fr\/","name":"Uni.lu","description":"Universit\u00e9 du Luxembourg","publisher":{"@id":"https:\/\/www.uni.lu\/fr\/#organization"},"alternateName":"Universit\u00e9 du Luxembourg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uni.lu\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.uni.lu\/fr\/#organization","name":"Universit\u00e9 du Luxembourg","alternateName":"Uni.lu","url":"https:\/\/www.uni.lu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2026\/03\/03120045\/UNIV_SM-Profile_1600x1600px-scaled.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2026\/03\/03120045\/UNIV_SM-Profile_1600x1600px-scaled.jpg","width":2560,"height":2560,"caption":"Universit\u00e9 du Luxembourg"},"image":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/11\/2026\/04\/24120552\/20200609-Belval-Campus_Henri-Goergen-23.jpg","sameAs":["https:\/\/www.facebook.com\/uni.lu","https:\/\/www.linkedin.com\/school\/university-of-luxembourg\/","https:\/\/www.instagram.com\/uni.lu","https:\/\/www.youtube.com\/@uni_lu","https:\/\/en.wikipedia.org\/wiki\/University_of_Luxembourg"],"email":"communication@uni.lu","telephone":"+352 46 66 44 1","address":{"@type":"PostalAddress","streetAddress":"2, place de l\u2019Universit\u00e9","addressLocality":"Esch-sur-Alzette","postalCode":"4365","addressCountry":"LU"},"description":"Universit\u00e9 du Luxembourg"}]}},"blog_id":11,"_links":{"self":[{"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/news\/1550"}],"collection":[{"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":1,"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/news\/1550\/revisions"}],"predecessor-version":[{"id":2502,"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/news\/1550\/revisions\/2502"}],"wp:attachment":[{"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/media?parent=1550"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/news-category?post=1550"},{"taxonomy":"news-topic","embeddable":true,"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/news-topic?post=1550"},{"taxonomy":"organisation","embeddable":true,"href":"https:\/\/www.uni.lu\/fr\/wp-json\/wp\/v2\/organisation?post=1550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}