{"id":2342,"date":"2024-02-15T09:24:54","date_gmt":"2024-02-15T08:24:54","guid":{"rendered":"https:\/\/www.uni.lu\/fhse-fr\/?post_type=news&#038;p=2342"},"modified":"2024-02-15T09:34:18","modified_gmt":"2024-02-15T08:34:18","slug":"quand-lhiver-part-en-fumee","status":"publish","type":"news","link":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/","title":{"rendered":"Quand l\u2019hiver part en fum\u00e9e"},"content":{"rendered":"\n<section class=\"wp-block-unilux-blocks-free-section section\"><div class=\"container xl:max-w-screen-xl\">\n<p>Les nuits du premier week-end de Car\u00eame sont un peu moins sombres au Luxembourg\u202f: les traditionnels Buergbrennen sont organis\u00e9s dans de nombreuses localit\u00e9s et r\u00e9unissent les habitants autour d\u2019un b\u00fbcher et des plats r\u00e9gionaux. Historienne sp\u00e9cialis\u00e9e dans la culture populaire, Sonja Kmec a men\u00e9 en 2021-2022 <a href=\"https:\/\/history.uni.lu\/research-on-fire\/\" target=\"_blank\" rel=\"noreferrer noopener\">un projet de recherche<\/a> sur cette tradition avec Catherine Lorent et Jean Reitz.<\/p>\n\n\n\n<p><strong>A quand remonte la tradition du Buergbrennen\u202f?<\/strong>&nbsp;<\/p>\n\n\n\n<p>\u00abLes premi\u00e8res traces remontent \u00e0 la fin du Moyen \u00c2ge. Certains pensent que les origines iraient jusqu\u2019\u00e0 l\u2019\u00e9poque gallo-romaine ou celtique mais cela est \u2013 \u00e0 ce stade \u2013 impossible \u00e0 prouver.&nbsp;<\/p>\n\n\n\n<p><strong>Le Buergbrennen est-il un rite typiquement luxembourgeois\u202f?<\/strong>&nbsp;<\/p>\n\n\n\n<p>\u00ab\u202fPas du tout, des feux saisonniers existent un peu partout en Europe. Ils ne sont pas forc\u00e9ment organis\u00e9s lors du Car\u00eame comme le Buergbrennen mais aussi autour de P\u00e2ques ou \u00e0 la Saint-Jean. Ces festivit\u00e9s ont toujours une symbolique agraire car elles sont calqu\u00e9es sur le rythme des semences et des r\u00e9coltes.&nbsp;<\/p>\n\n\n\n<p><strong>Qu\u2019ont montr\u00e9 vos recherches sur le Buergbrennen\u202f?<\/strong>&nbsp;<\/p>\n\n\n\n<p>\u00ab\u202fCette f\u00eate est toujours c\u00e9l\u00e9br\u00e9e en d\u00e9pit des nombreuses transformations de la soci\u00e9t\u00e9. D\u2019ailleurs, cette c\u00e9l\u00e9bration a connu plusieurs renouveaux. Par exemple dans les ann\u00e9es 1920 et 1930, elle a v\u00e9cu un regain d\u2019int\u00e9r\u00eat surtout au Sud du Luxembourg et autour de la capitale, bien qu\u2019\u00e0 la base elle soit une f\u00eate agraire et donc, plut\u00f4t fortement implant\u00e9e au Nord. Ensuite le Buergbrennen a connu d\u2019autres ravivements dans les ann\u00e9es 1970 et 1980 mais aussi au d\u00e9but des ann\u00e9es 2000. Force est de constater qu\u2019\u00e0 chaque fois que l\u2019on traverse une grande transformation soci\u00e9tale, les traditions gagnent en popularit\u00e9.<\/p>\n\n\n\n<p><strong>Comment expliquez-vous cela\u202f?<\/strong>&nbsp;<\/p>\n\n\n\n<p>\u00abPlus les rep\u00e8res sont chamboul\u00e9s, plus les traditions gagnent en importance. Les f\u00eates populaires traditionnelles comme le Buergbrennen apparaissent comme un r\u00e9f\u00e9rentiel dans une \u00e9poque o\u00f9 le sentiment que tout change tr\u00e8s vite est partag\u00e9. Nous avons comptabilis\u00e9 260 Buergbrennen en 2020 contre environ 100 \u00e0 la fin des ann\u00e9es 1960.&nbsp;<\/p>\n\n\n\n<p><strong>Il existe deux interpr\u00e9tations de ce b\u00fbcher\u202f: tant\u00f4t on chasse l\u2019hiver et tant\u00f4t on br\u00fble les sorci\u00e8res. Laquelle est la plus plausible\u202f?<\/strong>&nbsp;<\/p>\n\n\n\n<p>\u00ab\u202fA priori, c\u2019est pour br\u00fbler l\u2019hiver. Le b\u00fbcher oppose le froid de l\u2019hiver avec la chaleur du feu et incarne la lumi\u00e8re qu\u2019il d\u00e9gage. Cette lumi\u00e8re illustre aussi le retour de la clart\u00e9 avec l\u2019allongement des journ\u00e9es. Concernant les sorci\u00e8res, la plupart des historiens estiment que ces feux n\u2019ont pas de lien direct. Mais les premi\u00e8res traces \u00e9crites de cette tradition co\u00efncident avec l\u2019apog\u00e9e des proc\u00e8s de sorcellerie dans nos r\u00e9gions au 16<sup>e<\/sup> et 17<sup>e<\/sup> si\u00e8cles. Et certaines f\u00eates imitent des proc\u00e8s juridiques, o\u00f9 des poup\u00e9es de paille sont jug\u00e9es coupables pour d\u2019autres crimes et br\u00fbl\u00e9es \u2013 une sorte d\u2019expiation collective. La question m\u00e9riterait de s\u2019y pencher.&nbsp;<\/p>\n\n\n\n<p><strong>Le rituel du Buergbrennen a-t-il \u00e9volu\u00e9 ces derni\u00e8res ann\u00e9es\u202f?<\/strong>&nbsp;<\/p>\n\n\n\n<p>\u00ab\u202fLe cadre l\u00e9gal a \u00e9volu\u00e9\u202f: il est aujourd\u2019hui de plus en plus compliqu\u00e9 de faire un b\u00fbcher et la pr\u00e9sence des pompiers est requise. Dans les ann\u00e9es 1970, il n\u2019\u00e9tait pas rare de voir des pneus accroch\u00e9s au b\u00fbcher. Cela est inimaginable aujourd\u2019hui o\u00f9 l&rsquo;on ne peut br\u00fbler que du bois mort et non trait\u00e9 chimiquement.&nbsp;<\/p>\n\n\n\n<p>Une autre \u00e9volution concerne la dimension \u00e9v\u00e8nementielle du Buergbrennen, en particulier dans les grandes villes comme Luxembourg, Esch\/Alzette et Rodange. Des comit\u00e9s sp\u00e9cifiques organisent des animations et en viennent \u00e0 cr\u00e9er une f\u00eate beaucoup plus vaste avec des animations. Elles visent \u00e0 attirer des visiteurs ext\u00e9rieurs alors que dans les plus petites localit\u00e9s, le b\u00fbcher est simplement accompagn\u00e9 des airs de la fanfare locale.&nbsp;<\/p>\n\n\n\n<p><strong>On retrouve aussi souvent une offre en restauration avec des sp\u00e9cialit\u00e9s luxembourgeoises comme la Bouneschlupp. L\u2019occasion de mettre en avant la cuisine locale\u202f?<\/strong>&nbsp;<\/p>\n\n\n\n<p>\u00ab\u202fJe pense qu\u2019il s\u2019agit plut\u00f4t de mettre en avant la convivialit\u00e9. Au d\u00e9but des Buergbrennen, des omelettes g\u00e9antes au lard \u00e9taient cuisin\u00e9es par la collectivit\u00e9 dans un restaurant de la localit\u00e9. Puis au 20<sup>e<\/sup> si\u00e8cle les barbecues sont arriv\u00e9s. Et maintenant, c\u2019est comme dans toutes les f\u00eates de villages avec des frites, des c\u00f4telettes, de la Bouneschlupp ou Ierzebulli. Leur vente permet aussi de soutenir financi\u00e8rement les organisateurs.&nbsp;<\/p>\n\n\n\n<p><strong>L\u2019enjeu de pr\u00e9servation de l\u2019environnement peut-il menacer les Buergbrennen\u202f?<\/strong>&nbsp;<\/p>\n\n\n\n<p>\u00ab\u202fDes questions parlementaires ont d\u00e9j\u00e0 \u00e9t\u00e9 pos\u00e9es sur le sujet mais la tradition est multis\u00e9culaire et les r\u00e9ponses donn\u00e9es \u00e0 ce jour sont que le Buergbrennen est une exception. La tradition n\u2019est pas menac\u00e9e et est m\u00eame en \u00e9volution constante. Si la plupart des b\u00fbchers repr\u00e9sentent une croix, d\u2019autres prennent la forme d\u2019un ch\u00e2teau par exemple.&nbsp;<\/p>\n\n\n\n<p><strong>A ce propos, le Buergbrennen est-il pa\u00efen ou religieux\u202f? Car sa date est calqu\u00e9e sur les f\u00eates chr\u00e9tiennes alors qu\u2019il s\u2019agit \u00e0 la base d\u2019une coutume pa\u00efenne\u2026<\/strong>&nbsp;<\/p>\n\n\n\n<p>\u00ab\u202fL\u2019Eglise se montrait sceptique face \u00e0 cette c\u00e9l\u00e9bration au 16<sup>e<\/sup> si\u00e8cle. Les cur\u00e9s des villages ne voyaient pas d\u2019un bon \u0153il la promiscuit\u00e9 qu\u2019offrait le Buergbrennen entre les jeunes gens. Ensuite au 19<sup>e<\/sup> et d\u00e9but du 20<sup>e<\/sup> si\u00e8cle, l\u2019Eglise y a vu un int\u00e9r\u00eat car elle permettait de r\u00e9unir les villageois et donc, de le combiner avec une messe voire une procession autour du b\u00fbcher. Il est au final difficile de conclure \u00e0 la nature de la f\u00eate car villageois et parfois les hommes d\u2019Eglise avaient leur propre interpr\u00e9tation du christianisme et y int\u00e9graient des \u00e9l\u00e9ments magiques ou pa\u00efens. Ce qui est certain, c\u2019est que l\u2019Eglise a int\u00e9gr\u00e9 le Buergbrennen dans son calendrier.<\/p>\n\n\n<div class=\"py-48 first:pt-0 last:pb-0 wp-block-unilux-blocks-people-list\">\n    \n<h2 class=\"has-text-align-left wp-block-unilux-blocks-heading\"    >\n<\/h2>\n<ul class=\"flex flex-wrap -mx-16 wp-block-unilux-blocks-people-item-wrapper\">\n    <li class=\"w-full md:w-1\/2 p-16 wp-block-unilux-blocks-people-item-automated\"><div class=\"ulux-card card-people bg-theme\"><div class=\"list-people bg-theme\">\n    <div class=\"list-people__container\">\n        <div class=\"list-people__visual\">\n            <figure class=\"wp-block-dev4-reusable-blocks-image\">\n                <!-- Template Image Component: default -->\n<img decoding=\"async\" class=\"w-full\" width=\"\" height=\"\" rel=\"\" alt=\"Assoc. Prof Sonja KMEC\" src=\"https:\/\/www.uni.lu\/en\/person-image\/NTAwMDIxMDlfX1NvbmphIEtNRUM=\" srcset=\"https:\/\/www.uni.lu\/en\/person-image\/NTAwMDIxMDlfX1NvbmphIEtNRUM=--thumbnail 150w,https:\/\/www.uni.lu\/en\/person-image\/NTAwMDIxMDlfX1NvbmphIEtNRUM=--medium 300w,https:\/\/www.uni.lu\/en\/person-image\/NTAwMDIxMDlfX1NvbmphIEtNRUM=--medium_large 768w,https:\/\/www.uni.lu\/en\/person-image\/NTAwMDIxMDlfX1NvbmphIEtNRUM=--large 1024w,https:\/\/www.uni.lu\/en\/person-image\/NTAwMDIxMDlfX1NvbmphIEtNRUM=--1536x1536 1536w,https:\/\/www.uni.lu\/en\/person-image\/NTAwMDIxMDlfX1NvbmphIEtNRUM=--2048x2048 2048w\" loading=\"lazy\" \/><!-- end Image Component -->\n            <\/figure>\n        <\/div>\n        <div class=\"list-people__body\">\n            <h3 class=\"list-people__title\">Assoc. Prof Sonja KMEC<\/h3>\n            <p class=\"list-people__description\">Associate professor<\/p>\n            <div class=\"wp-block-unilux-blocks-simple-cta wp-block-unilux-blocks-people-item-automated\">\n    <a\n        href=\"https:\/\/www.uni.lu\/fhse-en\/people\/sonja-kmec\/\"\n        title=\"Assoc. Prof Sonja KMEC\"\n        class=\"link-text link-text--icon list-people__link link-absolute\"\n        target=\"\"\n    >\n        <span class=\"link-text__body\">\n            <span class=\"link-text__name\">Voir le profil<\/span>\n        <\/span>\n        <svg aria-hidden=\"true\" focusable=\"false\" class=\"icon icon-outline icon--arrow-right \"><use xlink:href=\"https:\/\/www.uni.lu\/wp-content\/themes\/unilux-theme\/assets\/images\/icons\/icons-outline.svg#icon--arrow-right\"><\/use><\/svg>    <\/a>\n<\/div>\n        <\/div>\n    <\/div>\n<\/div>\n<\/div><\/li><\/ul>\n\n<\/div>\n\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>Le Buergbrennen animera le week-end des 17 et 18 f\u00e9vrier un peu partout au Luxembourg. La professeure d\u2019histoire \u00e0 l\u2019Uni, Sonja Kmec, a \u00e9tudi\u00e9 cette tradition multis\u00e9culaire et ses \u00e9volutions. Chaud devant\u202f! <\/p>\n","protected":false},"author":33,"featured_media":2344,"template":"","format":"standard","meta":{"featured_image_focal_point":[],"show_featured_caption":false,"ulux_newsletter_groups":"","uluxPostTitle":"","uluxPrePostTitle":"","_trash_the_other_posts":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false},"news-category":[3],"news-topic":[16],"organisation":[170,146,173],"authorship":[33],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quand l\u2019hiver part en fum\u00e9e - FHSE actualit\u00e9s I Universit\u00e9 du Luxembourg<\/title>\n<meta name=\"description\" content=\"Le Buergbrennen animera le week-end des 17 et 18 f\u00e9vrier un peu partout au Luxembourg. La professeure d\u2019histoire \u00e0 l\u2019Uni, Sonja Kmec, a \u00e9tudi\u00e9 cette tradition multis\u00e9culaire et ses \u00e9volutions. Chaud devant\u202f!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quand l\u2019hiver part en fum\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Le Buergbrennen animera le week-end des 17 et 18 f\u00e9vrier un peu partout au Luxembourg. La professeure d\u2019histoire \u00e0 l\u2019Uni, Sonja Kmec, a \u00e9tudi\u00e9 cette tradition multis\u00e9culaire et ses \u00e9volutions. Chaud devant\u202f!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/\" \/>\n<meta property=\"og:site_name\" content=\"FHSE FR\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-15T08:34:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2024\/02\/buergbrennen.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1286\" \/>\n\t<meta property=\"og:image:height\" content=\"874\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/\"},\"author\":{\"name\":\"mchristen\",\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/#\/schema\/person\/c438f03d51b691a88d09778fc4b1e214\"},\"headline\":\"Quand l\u2019hiver part en fum\u00e9e\",\"datePublished\":\"2024-02-15T08:24:54+00:00\",\"dateModified\":\"2024-02-15T08:34:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/\"},\"wordCount\":1041,\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2024\/02\/buergbrennen.png\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/\",\"url\":\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/\",\"name\":\"Quand l\u2019hiver part en fum\u00e9e - FHSE actualit\u00e9s I Universit\u00e9 du Luxembourg\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2024\/02\/buergbrennen.png\",\"datePublished\":\"2024-02-15T08:24:54+00:00\",\"dateModified\":\"2024-02-15T08:34:18+00:00\",\"description\":\"Le Buergbrennen animera le week-end des 17 et 18 f\u00e9vrier un peu partout au Luxembourg. La professeure d\u2019histoire \u00e0 l\u2019Uni, Sonja Kmec, a \u00e9tudi\u00e9 cette tradition multis\u00e9culaire et ses \u00e9volutions. Chaud devant\u202f!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#primaryimage\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2024\/02\/buergbrennen.png\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2024\/02\/buergbrennen.png\",\"width\":1286,\"height\":874,\"caption\":\"Une croix en feu lors des festivit\u00e9s de Buergbrennen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uni.lu\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facult\u00e9 des Sciences Humaines, des Sciences de l\u2019\u00c9ducation et des Sciences Sociales\u200b\",\"item\":\"https:\/\/www.uni.lu\/fhse-fr\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"News\",\"item\":\"https:\/\/www.uni.lu\/fhse-fr\/news\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Quand l\u2019hiver part en fum\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/#website\",\"url\":\"https:\/\/www.uni.lu\/fhse-fr\/\",\"name\":\"FHSE\",\"description\":\"Facult\u00e9 des Sciences Humaines, des Sciences de l\u2019\u00c9ducation et des Sciences Sociales\u200b I Uni.lu\",\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/#organization\"},\"alternateName\":\"Facult\u00e9 des Sciences Humaines, des Sciences de l\u2019\u00c9ducation et des Sciences Sociales\u200b I Universit\u00e9 du Luxembourg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uni.lu\/fhse-fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/#organization\",\"name\":\"FHSE - Universit\u00e9 du Luxembourg I Uni.lu\",\"alternateName\":\"Facult\u00e9 des Sciences Humaines, des Sciences de l\u2019\u00c9ducation et des Sciences Sociales\u200b\",\"url\":\"https:\/\/www.uni.lu\/fhse-fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2026\/03\/03112325\/FHSE_SM-Profile_1600x1600px-scaled.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2026\/03\/03112325\/FHSE_SM-Profile_1600x1600px-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"FHSE - Universit\u00e9 du Luxembourg I Uni.lu\"},\"image\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2026\/04\/24144331\/20200609-Belval-Campus_Henri-Goergen-23.jpg\",\"sameAs\":[\"https:\/\/humanities.uni.lu\/\"],\"email\":\"communication@uni.lu\",\"telephone\":\"+3524666441\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"11, Porte des Sciences\",\"addressLocality\":\"Esch-sur-Alzette\",\"postalCode\":\"4365\",\"addressCountry\":\"LU\"},\"description\":\"Facult\u00e9 des Sciences Humaines, des Sciences de l\u2019\u00c9ducation et des Sciences Sociales\u200b I Uni.lu\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/#\/schema\/person\/c438f03d51b691a88d09778fc4b1e214\",\"name\":\"mchristen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/fhse-fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/16d82684b572872e8e543a3c7bfe637a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/16d82684b572872e8e543a3c7bfe637a?s=96&d=mm&r=g\",\"caption\":\"mchristen\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quand l\u2019hiver part en fum\u00e9e - FHSE actualit\u00e9s I Universit\u00e9 du Luxembourg","description":"Le Buergbrennen animera le week-end des 17 et 18 f\u00e9vrier un peu partout au Luxembourg. La professeure d\u2019histoire \u00e0 l\u2019Uni, Sonja Kmec, a \u00e9tudi\u00e9 cette tradition multis\u00e9culaire et ses \u00e9volutions. Chaud devant\u202f!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/","og_locale":"fr_FR","og_type":"article","og_title":"Quand l\u2019hiver part en fum\u00e9e","og_description":"Le Buergbrennen animera le week-end des 17 et 18 f\u00e9vrier un peu partout au Luxembourg. La professeure d\u2019histoire \u00e0 l\u2019Uni, Sonja Kmec, a \u00e9tudi\u00e9 cette tradition multis\u00e9culaire et ses \u00e9volutions. Chaud devant\u202f!","og_url":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/","og_site_name":"FHSE FR","article_modified_time":"2024-02-15T08:34:18+00:00","og_image":[{"width":1286,"height":874,"url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2024\/02\/buergbrennen.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#article","isPartOf":{"@id":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/"},"author":{"name":"mchristen","@id":"https:\/\/www.uni.lu\/fhse-fr\/#\/schema\/person\/c438f03d51b691a88d09778fc4b1e214"},"headline":"Quand l\u2019hiver part en fum\u00e9e","datePublished":"2024-02-15T08:24:54+00:00","dateModified":"2024-02-15T08:34:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/"},"wordCount":1041,"publisher":{"@id":"https:\/\/www.uni.lu\/fhse-fr\/#organization"},"image":{"@id":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2024\/02\/buergbrennen.png","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/","url":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/","name":"Quand l\u2019hiver part en fum\u00e9e - FHSE actualit\u00e9s I Universit\u00e9 du Luxembourg","isPartOf":{"@id":"https:\/\/www.uni.lu\/fhse-fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#primaryimage"},"image":{"@id":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2024\/02\/buergbrennen.png","datePublished":"2024-02-15T08:24:54+00:00","dateModified":"2024-02-15T08:34:18+00:00","description":"Le Buergbrennen animera le week-end des 17 et 18 f\u00e9vrier un peu partout au Luxembourg. La professeure d\u2019histoire \u00e0 l\u2019Uni, Sonja Kmec, a \u00e9tudi\u00e9 cette tradition multis\u00e9culaire et ses \u00e9volutions. Chaud devant\u202f!","breadcrumb":{"@id":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#primaryimage","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2024\/02\/buergbrennen.png","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2024\/02\/buergbrennen.png","width":1286,"height":874,"caption":"Une croix en feu lors des festivit\u00e9s de Buergbrennen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uni.lu\/fhse-fr\/news\/quand-lhiver-part-en-fumee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uni.lu\/fr"},{"@type":"ListItem","position":2,"name":"Facult\u00e9 des Sciences Humaines, des Sciences de l\u2019\u00c9ducation et des Sciences Sociales\u200b","item":"https:\/\/www.uni.lu\/fhse-fr\/"},{"@type":"ListItem","position":3,"name":"News","item":"https:\/\/www.uni.lu\/fhse-fr\/news\/"},{"@type":"ListItem","position":4,"name":"Quand l\u2019hiver part en fum\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.uni.lu\/fhse-fr\/#website","url":"https:\/\/www.uni.lu\/fhse-fr\/","name":"FHSE","description":"Facult\u00e9 des Sciences Humaines, des Sciences de l\u2019\u00c9ducation et des Sciences Sociales\u200b I Uni.lu","publisher":{"@id":"https:\/\/www.uni.lu\/fhse-fr\/#organization"},"alternateName":"Facult\u00e9 des Sciences Humaines, des Sciences de l\u2019\u00c9ducation et des Sciences Sociales\u200b I Universit\u00e9 du Luxembourg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uni.lu\/fhse-fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.uni.lu\/fhse-fr\/#organization","name":"FHSE - Universit\u00e9 du Luxembourg I Uni.lu","alternateName":"Facult\u00e9 des Sciences Humaines, des Sciences de l\u2019\u00c9ducation et des Sciences Sociales\u200b","url":"https:\/\/www.uni.lu\/fhse-fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/fhse-fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2026\/03\/03112325\/FHSE_SM-Profile_1600x1600px-scaled.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2026\/03\/03112325\/FHSE_SM-Profile_1600x1600px-scaled.jpg","width":2560,"height":2560,"caption":"FHSE - Universit\u00e9 du Luxembourg I Uni.lu"},"image":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/16\/2026\/04\/24144331\/20200609-Belval-Campus_Henri-Goergen-23.jpg","sameAs":["https:\/\/humanities.uni.lu\/"],"email":"communication@uni.lu","telephone":"+3524666441","address":{"@type":"PostalAddress","streetAddress":"11, Porte des Sciences","addressLocality":"Esch-sur-Alzette","postalCode":"4365","addressCountry":"LU"},"description":"Facult\u00e9 des Sciences Humaines, des Sciences de l\u2019\u00c9ducation et des Sciences Sociales\u200b I Uni.lu"},{"@type":"Person","@id":"https:\/\/www.uni.lu\/fhse-fr\/#\/schema\/person\/c438f03d51b691a88d09778fc4b1e214","name":"mchristen","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/fhse-fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/16d82684b572872e8e543a3c7bfe637a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/16d82684b572872e8e543a3c7bfe637a?s=96&d=mm&r=g","caption":"mchristen"}}]}},"blog_id":16,"_links":{"self":[{"href":"https:\/\/www.uni.lu\/fhse-fr\/wp-json\/wp\/v2\/news\/2342"}],"collection":[{"href":"https:\/\/www.uni.lu\/fhse-fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.uni.lu\/fhse-fr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fhse-fr\/wp-json\/wp\/v2\/users\/33"}],"version-history":[{"count":2,"href":"https:\/\/www.uni.lu\/fhse-fr\/wp-json\/wp\/v2\/news\/2342\/revisions"}],"predecessor-version":[{"id":2345,"href":"https:\/\/www.uni.lu\/fhse-fr\/wp-json\/wp\/v2\/news\/2342\/revisions\/2345"}],"wp:authorship":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fhse-fr\/wp-json\/wp\/v2\/users\/33"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fhse-fr\/wp-json\/wp\/v2\/media\/2344"}],"wp:attachment":[{"href":"https:\/\/www.uni.lu\/fhse-fr\/wp-json\/wp\/v2\/media?parent=2342"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/www.uni.lu\/fhse-fr\/wp-json\/wp\/v2\/news-category?post=2342"},{"taxonomy":"news-topic","embeddable":true,"href":"https:\/\/www.uni.lu\/fhse-fr\/wp-json\/wp\/v2\/news-topic?post=2342"},{"taxonomy":"organisation","embeddable":true,"href":"https:\/\/www.uni.lu\/fhse-fr\/wp-json\/wp\/v2\/organisation?post=2342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}