{"id":2240,"date":"2026-05-05T13:51:06","date_gmt":"2026-05-05T11:51:06","guid":{"rendered":"https:\/\/www.uni.lu\/fhse-de\/?post_type=events&#038;p=2240"},"modified":"2026-05-06T14:59:20","modified_gmt":"2026-05-06T12:59:20","slug":"vortrag-regress-und-progress-zur-entstehung-des-neuen","status":"publish","type":"events","link":"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/","title":{"rendered":"Regress und Progress. Zur Entstehung des Neuen"},"content":{"rendered":"\n<section class=\"wp-block-unilux-blocks-free-section section\"><div class=\"container xl:max-w-screen-xl\">\n<h3 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"thema\"\n    >\nThema<\/h3>\n\n\n\n<p>Wir befinden uns in einem Spannungsfeld zwischen bedeutenden wissenschaftlichen und technischen Errungenschaften, denen kaum Grenzen gesetzt zu sein scheinen, und einem tiefen Zweifel an ihrem moralischen, sozialen und anthropologischen Fortschritt; in Anbetracht vor allem einer Gewalt, ja Barbarei, die wir l\u00e4ngst als \u00fcberwunden zu haben glaubten. Auch wenn einige sie als \u00ab vorgeschichtlich \u00bb bezeichnen, l\u00e4sst sich leicht zeigen, erstens dass sie in regelm\u00e4\u00dfigen Abst\u00e4nden in die Geschichte einbricht und dort f\u00fcr einen Umbruch sorgt; zweitens, dass sie ein untr\u00fcgliches Zeichen daf\u00fcr ist, dass wir mitten in einem solchen begriffen sind, ohne dass wir sein ganzes Ausma\u00df bereist \u00fcberblicken k\u00f6nnen.<\/p>\n\n\n\n<p>Wenn ich zeigen m\u00f6chte, dass es keinen Aufbruch ohne Umbruch, keinen Progress ohne Regress gibt, dann gehe ich auch von meiner klinischen Arbeit aus, die ich nicht losgel\u00f6st von ihrem sozialen Umfeld und ihren politischen Folgen betrachten m\u00f6chte. Es handelt sich dabei nicht um einen nat\u00fcrlichen Vorgang, sondern um die gr\u00f6\u00dfte Herausforderung, die sich f\u00fcr jede Epoche, jede Generation, sowohl f\u00fcr den Einzelnen als auch die Allgemeinheit, stellt. Immer wieder sind die h\u00f6chsten kulturellen G\u00fcter einer gro\u00dfen Bedrohung ausgesetzt, woraufhin sie nicht unbedingt verschwinden, sondern wieder neu erfunden werden m\u00fcssen. Dem Neuen kommt somit eine hervorragende sowohl epistemische als auch ethische Bedeutung zu, die f\u00fcr das Individuum und die Gesellschaft gleicherma\u00dfen gilt.<\/p>\n<\/div><\/section>\n\n\n\n<section class=\"py-0 wp-block-unilux-blocks-free-section section\"><div class=\"container xl:max-w-screen-xl\"><div class=\"flex flex-wrap -mx-16  wp-block-unilux-blocks-highlighted-person-list\">\n    <div class=\"w-full md:w-1\/2 px-16  wp-block-unilux-blocks-highlighted-person-list-item\">\n    \n<h3 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"referent\"\n    >\nReferent<\/h3>\n\n<div class=\"wp-block-unilux-blocks-wrapper list-people bg-theme\">\n<div class=\"wp-block-unilux-blocks-wrapper list-people__container\">\n<div class=\"wp-block-unilux-blocks-wrapper list-people__visual\"><figure class=\"wp-block-dev4-reusable-blocks-image w-full object-fit--cover\">\n    \n<img decoding=\"async\" class=\"wp-block-image unilux-custom-image-block\"\n                alt=\"\"\n            src=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/05\/05134214\/322B24CA-2E85-41C2-BC45-AF7110FCE7F7_1_105_c-003.jpeg\"\n                srcset=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/05\/05134214\/322B24CA-2E85-41C2-BC45-AF7110FCE7F7_1_105_c-003-300x300.jpeg 300w, https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/05\/05134214\/322B24CA-2E85-41C2-BC45-AF7110FCE7F7_1_105_c-003-150x150.jpeg 150w, https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/05\/05134214\/322B24CA-2E85-41C2-BC45-AF7110FCE7F7_1_105_c-003.jpeg 480w\"\n                style=\"object-position: 53.00% 52.00%; font-family: &quot;object-fit: cover; object-position: 53.00% 52.00%;&quot;; aspect-ratio: 1\/1; object-fit: cover; width: 100%;\"\n        loading=\"lazy\"\n\/>    <\/figure><\/div>\n\n\n\n<div class=\"wp-block-unilux-blocks-wrapper list-people__body\">\n<h5 class=\"list-people__title has-text-align-left wp-block-unilux-blocks-heading\"        id=\"dr-andre-michels\"\n    >\nDr. Andr\u00e9 Michels<\/h5>\n\n\n\n<p class=\"list-people__description wp-block-unilux-blocks-plain-text\">Psychoanalytiker und Psychiater<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-unilux-blocks-free-section section\"><div class=\"container xl:max-w-screen-xl\"><div class=\"flex flex-wrap -mx-16  wp-block-unilux-blocks-highlighted-person-list\">\n    <div class=\"w-full md:w-1\/2 px-16  wp-block-unilux-blocks-highlighted-person-list-item\">\n    \n<h3 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"kontakt\"\n    >\nKontakt<\/h3>\n\n<div class=\"wp-block-unilux-blocks-wrapper list-people bg-theme\">\n<div class=\"wp-block-unilux-blocks-wrapper list-people__container\">\n<div class=\"wp-block-unilux-blocks-wrapper list-people__visual\"><figure class=\"wp-block-dev4-reusable-blocks-image w-full object-fit--cover\">\n    \n<img decoding=\"async\" class=\"wp-block-image unilux-custom-image-block\"\n                alt=\"\"\n            src=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2025\/02\/PR2_5289.png\"\n                srcset=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2025\/02\/PR2_5289-300x300.png 300w, https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2025\/02\/PR2_5289-1024x1024.png 1024w, https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2025\/02\/PR2_5289-150x150.png 150w, https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2025\/02\/PR2_5289-768x768.png 768w, https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2025\/02\/PR2_5289.png 1500w\"\n                style=\"object-position: 50.00% 52.00%; font-family: &quot;object-fit: cover; object-position: 50.00% 52.00%;&quot;; aspect-ratio: 1\/1; object-fit: cover; width: 100%;\"\n        loading=\"lazy\"\n\/>    <\/figure><\/div>\n\n\n\n<div class=\"wp-block-unilux-blocks-wrapper list-people__body\">\n<h5 class=\"list-people__title has-text-align-left wp-block-unilux-blocks-heading\"        id=\"dr-jean-marie-weber\"\n    >\nDr. Jean-Marie Weber<\/h5>\n\n\n\n<p class=\"list-people__description wp-block-unilux-blocks-plain-text\">Assistenzprofessor  (in Rente) und Psychoanalytiker, Universit\u00e4t Luxemburg<\/p>\n\n<div class=\"wp-block-unilux-blocks-simple-cta\">\n    <a\n        href=\"https:\/\/www.uni-trier.de\/universitaet\/fachbereiche-faecher\/fachbereich-iii\/faecher\/politikwissenschaft\/team\/internationale-beziehungen-und-aussenpolitik\/team\/froehlich-manuel\"\n        title=\"Learn More\"\n        class=\"link-text link-text--icon link-absolute\"\n        target=\"\"\n    >\n        <span class=\"link-text__body\">\n            <span class=\"link-text__name\">E-mail<\/span>\n        <\/span>\n        <svg aria-hidden=\"true\" focusable=\"false\" class=\"icon icon-outline icon--arrow-right \"><use xlink:href=\"https:\/\/www.uni.lu\/wp-content\/themes\/unilux-theme\/assets\/images\/icons\/icons-outline.svg#icon--arrow-right\"><\/use><\/svg>    <\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"py-0 wp-block-unilux-blocks-free-section section\"><div class=\"container xl:max-w-screen-xl\">\n<p><strong>Der Vortrag findet im Rahmen der Reihe <a href=\"https:\/\/www.uni.lu\/fhse-de\/news\/vortragsreihe-fortschritt-und-regression-in-unserer-gesellschaft\/\">Fortschritt und Regression in unserer Gesellschaft<\/a> statt. Die Vortragsreihe wird organisiert von der Arbeitsgruppe &#8218;Humanities &amp; Religion&#8216; der Universit\u00e4t Luxemburg. Zu den Mitgliedern der Gruppe geh\u00f6ren Gerhard Beesterm\u00f6ller, Jean Braun, Roger Davids, Ren\u00e9 Gonner, Peter Voss und Jean-Marie Weber.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-unilux-blocks-custom-buttons btn-list\"><li class=\"wp-block-unilux-blocks-custom-button\"    aria-disabled=\"false\"\n    >\n    <a\n        role=\"link\"\n        aria-disabled=\"false\"\n                    href=\"https:\/\/www.uni.lu\/fhse-de\/calendar?post_type=events&#038;p=2240&#038;calendar\"\n                target=\"_self\"\n        class=\"btn btn--primary\"\n            >Zum Kalender hinzuf\u00fcgen<\/a>\n<\/li>\n\n\n<li class=\"wp-block-unilux-blocks-custom-button\"    aria-disabled=\"false\"\n    >\n    <a\n        role=\"link\"\n        aria-disabled=\"false\"\n                    href=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/05\/05135227\/20260511_Regress-und-Progress_Andre-Michels.pdf\"\n                target=\"_self\"\n        class=\"btn btn--primary\"\n            >Poster<\/a>\n<\/li>\n<\/ul>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-unilux-blocks-free-section section\"><div class=\"container xl:max-w-screen-xl\">\n<p>Photo by <a href=\"https:\/\/unsplash.com\/photos\/KFIjzXYg1RM\">Jeremy Bishop<\/a> on <a href=\"https:\/\/unsplash.com\/\">Unsplash<\/a><\/p>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":197,"featured_media":2242,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"featured_image_focal_point":[],"show_featured_caption":false,"ulux_newsletter_groups":"","uluxPostTitle":"","uluxPrePostTitle":"","_trash_the_other_posts":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"event_start_date":"2026-05-11 19:00:00","event_end_date":"2026-05-11 21:00:00","event_speaker_name":"Andr\u00e9 Michels","event_speaker_link":"","event_is_online":false,"event_location":"Campus Limpertsberg, B\u00e2timent des Sciences, Raum BSC 0.03","event_street":"162a, avenue de la Fa\u00efencerie","event_location_link":"","event_zip_code":"1511","event_city":"Luxembourg","event_country":"Luxembourg"},"events-topic":[305,311],"events-type":[318],"organisation":[170,178,146],"authorship":[197],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Regress und Progress. Zur Entstehung des Neuen - FHSE I Uni.lu<\/title>\n<meta name=\"description\" content=\"Wir befinden uns in einem Spannungsfeld zwischen bedeutenden wissenschaftlichen und technischen Errungenschaften, denen kaum Grenzen gesetzt zu sein\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regress und Progress. Zur Entstehung des Neuen\" \/>\n<meta property=\"og:description\" content=\"Wir befinden uns in einem Spannungsfeld zwischen bedeutenden wissenschaftlichen und technischen Errungenschaften, denen kaum Grenzen gesetzt zu sein\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/\" \/>\n<meta property=\"og:site_name\" content=\"FHSE DE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T12:59:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/05\/05134644\/europeana-xBH8XHpxTr0-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1782\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/\",\"url\":\"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/\",\"name\":\"Regress und Progress. Zur Entstehung des Neuen - FHSE I Uni.lu\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/05\/05134644\/europeana-xBH8XHpxTr0-unsplash-scaled.jpg\",\"datePublished\":\"2026-05-05T11:51:06+00:00\",\"dateModified\":\"2026-05-06T12:59:20+00:00\",\"description\":\"Wir befinden uns in einem Spannungsfeld zwischen bedeutenden wissenschaftlichen und technischen Errungenschaften, denen kaum Grenzen gesetzt zu sein\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/#primaryimage\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/05\/05134644\/europeana-xBH8XHpxTr0-unsplash-scaled.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/05\/05134644\/europeana-xBH8XHpxTr0-unsplash-scaled.jpg\",\"width\":2560,\"height\":1782},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uni.lu\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fakult\u00e4t f\u00fcr Geisteswissenschaften, Erziehungswissenschaften und Sozialwissenschaften\",\"item\":\"https:\/\/www.uni.lu\/fhse-de\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Events\",\"item\":\"https:\/\/www.uni.lu\/fhse-de\/events\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Regress und Progress. Zur Entstehung des Neuen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uni.lu\/fhse-de\/#website\",\"url\":\"https:\/\/www.uni.lu\/fhse-de\/\",\"name\":\"FHSE\",\"description\":\"Fakult\u00e4t f\u00fcr Geisteswissenschaften, Erziehungswissenschaften und Sozialwissenschaften I Uni.lu\",\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/fhse-de\/#organization\"},\"alternateName\":\"Fakult\u00e4t f\u00fcr Geisteswissenschaften, Erziehungswissenschaften und Sozialwissenschaften I Universit\u00e4t Luxemburg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uni.lu\/fhse-de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.uni.lu\/fhse-de\/#organization\",\"name\":\"FHSE - Universit\u00e4t Luxemburg I Uni.lu\",\"alternateName\":\"Fakult\u00e4t f\u00fcr Geisteswissenschaften, Erziehungswissenschaften und Sozialwissenschaften\",\"url\":\"https:\/\/www.uni.lu\/fhse-de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.uni.lu\/fhse-de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/03\/03112457\/FHSE_SM-Profile_1600x1600px-scaled.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/03\/03112457\/FHSE_SM-Profile_1600x1600px-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"FHSE - Universit\u00e4t Luxemburg I Uni.lu\"},\"image\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/04\/24144331\/20200609-Belval-Campus_Henri-Goergen-23.jpg\",\"sameAs\":[\"https:\/\/humanities.uni.lu\/\"],\"email\":\"communication@uni.lu\",\"telephone\":\"+3524666441\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"11, Porte des Sciences\",\"addressLocality\":\"Esch-sur-Alzette\",\"postalCode\":\"4365\",\"addressCountry\":\"LU\"},\"description\":\"Fakult\u00e4t f\u00fcr Geisteswissenschaften, Erziehungswissenschaften und Sozialwissenschaften I Uni.lu\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Regress und Progress. Zur Entstehung des Neuen - FHSE I Uni.lu","description":"Wir befinden uns in einem Spannungsfeld zwischen bedeutenden wissenschaftlichen und technischen Errungenschaften, denen kaum Grenzen gesetzt zu sein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/","og_locale":"de_DE","og_type":"article","og_title":"Regress und Progress. Zur Entstehung des Neuen","og_description":"Wir befinden uns in einem Spannungsfeld zwischen bedeutenden wissenschaftlichen und technischen Errungenschaften, denen kaum Grenzen gesetzt zu sein","og_url":"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/","og_site_name":"FHSE DE","article_modified_time":"2026-05-06T12:59:20+00:00","og_image":[{"width":2560,"height":1782,"url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/05\/05134644\/europeana-xBH8XHpxTr0-unsplash-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/","url":"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/","name":"Regress und Progress. Zur Entstehung des Neuen - FHSE I Uni.lu","isPartOf":{"@id":"https:\/\/www.uni.lu\/fhse-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/#primaryimage"},"image":{"@id":"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/05\/05134644\/europeana-xBH8XHpxTr0-unsplash-scaled.jpg","datePublished":"2026-05-05T11:51:06+00:00","dateModified":"2026-05-06T12:59:20+00:00","description":"Wir befinden uns in einem Spannungsfeld zwischen bedeutenden wissenschaftlichen und technischen Errungenschaften, denen kaum Grenzen gesetzt zu sein","breadcrumb":{"@id":"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/#primaryimage","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/05\/05134644\/europeana-xBH8XHpxTr0-unsplash-scaled.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/05\/05134644\/europeana-xBH8XHpxTr0-unsplash-scaled.jpg","width":2560,"height":1782},{"@type":"BreadcrumbList","@id":"https:\/\/www.uni.lu\/fhse-de\/events\/vortrag-regress-und-progress-zur-entstehung-des-neuen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uni.lu\/de"},{"@type":"ListItem","position":2,"name":"Fakult\u00e4t f\u00fcr Geisteswissenschaften, Erziehungswissenschaften und Sozialwissenschaften","item":"https:\/\/www.uni.lu\/fhse-de\/"},{"@type":"ListItem","position":3,"name":"Events","item":"https:\/\/www.uni.lu\/fhse-de\/events\/"},{"@type":"ListItem","position":4,"name":"Regress und Progress. Zur Entstehung des Neuen"}]},{"@type":"WebSite","@id":"https:\/\/www.uni.lu\/fhse-de\/#website","url":"https:\/\/www.uni.lu\/fhse-de\/","name":"FHSE","description":"Fakult\u00e4t f\u00fcr Geisteswissenschaften, Erziehungswissenschaften und Sozialwissenschaften I Uni.lu","publisher":{"@id":"https:\/\/www.uni.lu\/fhse-de\/#organization"},"alternateName":"Fakult\u00e4t f\u00fcr Geisteswissenschaften, Erziehungswissenschaften und Sozialwissenschaften I Universit\u00e4t Luxemburg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uni.lu\/fhse-de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.uni.lu\/fhse-de\/#organization","name":"FHSE - Universit\u00e4t Luxemburg I Uni.lu","alternateName":"Fakult\u00e4t f\u00fcr Geisteswissenschaften, Erziehungswissenschaften und Sozialwissenschaften","url":"https:\/\/www.uni.lu\/fhse-de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.uni.lu\/fhse-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/03\/03112457\/FHSE_SM-Profile_1600x1600px-scaled.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/03\/03112457\/FHSE_SM-Profile_1600x1600px-scaled.jpg","width":2560,"height":2560,"caption":"FHSE - Universit\u00e4t Luxemburg I Uni.lu"},"image":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/15\/2026\/04\/24144331\/20200609-Belval-Campus_Henri-Goergen-23.jpg","sameAs":["https:\/\/humanities.uni.lu\/"],"email":"communication@uni.lu","telephone":"+3524666441","address":{"@type":"PostalAddress","streetAddress":"11, Porte des Sciences","addressLocality":"Esch-sur-Alzette","postalCode":"4365","addressCountry":"LU"},"description":"Fakult\u00e4t f\u00fcr Geisteswissenschaften, Erziehungswissenschaften und Sozialwissenschaften I Uni.lu"}]}},"_links":{"self":[{"href":"https:\/\/www.uni.lu\/fhse-de\/wp-json\/wp\/v2\/events\/2240"}],"collection":[{"href":"https:\/\/www.uni.lu\/fhse-de\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/www.uni.lu\/fhse-de\/wp-json\/wp\/v2\/types\/events"}],"author":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fhse-de\/wp-json\/wp\/v2\/users\/197"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fhse-de\/wp-json\/wp\/v2\/comments?post=2240"}],"version-history":[{"count":5,"href":"https:\/\/www.uni.lu\/fhse-de\/wp-json\/wp\/v2\/events\/2240\/revisions"}],"predecessor-version":[{"id":2281,"href":"https:\/\/www.uni.lu\/fhse-de\/wp-json\/wp\/v2\/events\/2240\/revisions\/2281"}],"wp:authorship":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fhse-de\/wp-json\/wp\/v2\/users\/197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fhse-de\/wp-json\/wp\/v2\/media\/2242"}],"wp:attachment":[{"href":"https:\/\/www.uni.lu\/fhse-de\/wp-json\/wp\/v2\/media?parent=2240"}],"wp:term":[{"taxonomy":"events-topic","embeddable":true,"href":"https:\/\/www.uni.lu\/fhse-de\/wp-json\/wp\/v2\/events-topic?post=2240"},{"taxonomy":"events-type","embeddable":true,"href":"https:\/\/www.uni.lu\/fhse-de\/wp-json\/wp\/v2\/events-type?post=2240"},{"taxonomy":"organisation","embeddable":true,"href":"https:\/\/www.uni.lu\/fhse-de\/wp-json\/wp\/v2\/organisation?post=2240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}