{"id":3280,"date":"2026-02-17T09:57:36","date_gmt":"2026-02-17T08:57:36","guid":{"rendered":"https:\/\/www.uni.lu\/fdef-fr\/?post_type=events&#038;p=3280"},"modified":"2026-02-17T09:57:57","modified_gmt":"2026-02-17T08:57:57","slug":"reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3","status":"publish","type":"events","link":"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/","title":{"rendered":"R\u00e9flexions sur la jurisprudence civile au Luxembourg. L\u2019exemple du droit des contrats"},"content":{"rendered":"\n<section class=\"py-0 wp-block-unilux-blocks-free-section section\"><div class=\"container xl:max-w-screen-xl\">\n<ul class=\"wp-block-unilux-blocks-custom-buttons btn-list\"><li class=\"wp-block-unilux-blocks-custom-button\"    aria-disabled=\"false\"\n    >\n    <a\n        role=\"link\"\n        aria-disabled=\"false\"\n                    href=\"https:\/\/www.eventbrite.fr\/e\/billets-conference-grdpl-reflexions-sur-la-jurisprudence-civile-au-luxembourg-1978820563574?aff=oddtdtcreator\"\n                target=\"_blank\"\n        class=\"btn btn--primary\"\n            >Je m&rsquo;inscris<\/a>\n<\/li>\n\n\n<li class=\"wp-block-unilux-blocks-custom-button\"    aria-disabled=\"false\"\n    >\n    <a\n        role=\"link\"\n        aria-disabled=\"false\"\n                    href=\"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/calendar\"\n                target=\"_self\"\n        class=\"btn btn--secondary\"\n            >Ajouter au calendrier<\/a>\n<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-unilux-blocks-spacer is-spacer-size-sm\"><\/div>\n\n\n<h5 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"resume\"\n    >\nR\u00e9sum\u00e9<\/h5>\n\n\n\n<p>A l\u2019occasion de la parution de la seconde \u00e9dition de son manuel de droit luxembourgeois des contrats, et \u00e0 partir de l\u2019exp\u00e9rience que la r\u00e9daction de cette nouvelle version lui a procur\u00e9e, Pascal Ancel est amen\u00e9 \u00e0 se livrer \u00e0 une r\u00e9flexion sur la jurisprudence civile luxembourgeoise. Alors que la premi\u00e8re \u00e9dition avait \u00e9t\u00e9 con\u00e7ue dans une approche principalement p\u00e9dagogique, \u00e9clair\u00e9e par la seule jurisprudence publi\u00e9e, l\u2019auteur a souhait\u00e9 ouvrir davantage son ouvrage aux praticiens, notamment pour combler le vide laiss\u00e9 par l\u2019absence de r\u00e9\u00e9dition de l\u2019ouvrage d\u2019Olivier Poelmans. Cet objectif supposait d\u2019enrichir le propos de nombreuses r\u00e9f\u00e9rences jurisprudentielles, y compris tr\u00e8s r\u00e9centes, en profitant des progr\u00e8s r\u00e9alis\u00e9s dans l\u2019acc\u00e8s aux d\u00e9cisions non publi\u00e9es. <\/p>\n\n\n\n<p>La recherche approfondie r\u00e9alis\u00e9e \u00e0 cet effet, ainsi que, en parall\u00e8le, dans le cadre des travaux men\u00e9s pour la pr\u00e9paration de l\u2019avant-projet de r\u00e9forme du droit des contrats, a permis \u00e0 l\u2019auteur de mesurer la sp\u00e9cificit\u00e9, du moins dans la mati\u00e8re contractuelle, de la jurisprudence civile luxembourgeoise, si on cherche \u00e0 la comparer avec le mod\u00e8le fran\u00e7ais. Cette sp\u00e9cificit\u00e9 tient d\u2019abord aux d\u00e9cisions elles-m\u00eames, quant \u00e0 la mani\u00e8re dont elles sont structur\u00e9es, r\u00e9dig\u00e9es, et quant aux sources dont elles s\u2019inspirent explicitement. Elle se manifeste ensuite et surtout quant \u00e0 l\u2019utilisation qui peut \u00eatre faite de ces d\u00e9cisions pour construire ce qu\u2019est, au sens propre, une \u00ab jurisprudence \u00bb, en raison des d\u00e9fauts persistants malgr\u00e9 les progr\u00e8s des modes d\u2019acc\u00e8s aux d\u00e9cisions, de la faiblesse des canaux de diffusion et de s\u00e9lection de celles-ci, et de l\u2019insuffisance, jusqu\u2019\u00e0 maintenant, d\u2019une doctrine proprement luxembourgeoise apte \u00e0 en tirer des normes par ses commentaires et ses mises en relation.<\/p>\n\n\n\n<p><strong>Interv\u00e9nant:<\/strong> Pascal Ancel (<em>Professeur \u00e9m\u00e9rite de l\u2019Universit\u00e9 du Luxembourg)<\/em><\/p>\n\n\n\n<p><strong>Discutant:<\/strong> <a href=\"https:\/\/www.uni.lu\/fdef-en\/people\/david-hiez\/\">David Hiez<\/a> (<em>Professeur \u00e0 l\u2019Universit\u00e9 du Luxembourg<\/em>)<\/p>\n\n\n<div class=\"wp-block-unilux-blocks-spacer is-spacer-size-sm\"><\/div>\n\n\n<h5 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"langue\"\n    >\nLangue<\/h5>\n\n\n\n<p>Fran\u00e7ais.<\/p>\n\n\n\n<p>Cette conf\u00e9rence est gratuite. L\u2019inscription est obligatoire.<\/p>\n\n\n\n<p>Cette conf\u00e9rence pourra \u00eatre prise en compte dans la formation des avocats.<\/p>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":85,"featured_media":2746,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"featured_image_focal_point":[],"show_featured_caption":false,"ulux_newsletter_groups":"","uluxPostTitle":"","uluxPrePostTitle":"","_trash_the_other_posts":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"event_start_date":"2026-02-03 18:00:00","event_end_date":"2026-02-03 20:00:00","event_speaker_name":"","event_speaker_link":"","event_is_online":false,"event_location":"B\u00e2timent Weicker","event_street":"4, rue Alphonse Weicker","event_location_link":"https:\/\/www.uni.lu\/fr\/a-propos\/campus\/batiment-weicker\/","event_zip_code":"2721","event_city":"Luxembourg","event_country":"Luxembourg"},"events-topic":[305],"events-type":[317,322,323],"organisation":[103,100,106],"authorship":[85],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u00e9flexions sur la jurisprudence civile au Luxembourg. L\u2019exemple du droit des contrats - FDEF I Uni.lu<\/title>\n<meta name=\"description\" content=\"A l\u2019occasion de la parution de la seconde \u00e9dition de son manuel de droit luxembourgeois des contrats, et \u00e0 partir de l\u2019exp\u00e9rience que la r\u00e9daction de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9flexions sur la jurisprudence civile au Luxembourg. L\u2019exemple du droit des contrats\" \/>\n<meta property=\"og:description\" content=\"A l\u2019occasion de la parution de la seconde \u00e9dition de son manuel de droit luxembourgeois des contrats, et \u00e0 partir de l\u2019exp\u00e9rience que la r\u00e9daction de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/\" \/>\n<meta property=\"og:site_name\" content=\"FDEF FR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uni.FDEF.lu\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-17T08:57:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2025\/01\/AdobeStock_575311679-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"921\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/\",\"url\":\"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/\",\"name\":\"R\u00e9flexions sur la jurisprudence civile au Luxembourg. L\u2019exemple du droit des contrats - FDEF I Uni.lu\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/fdef-fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2025\/01\/AdobeStock_575311679-scaled.jpeg\",\"datePublished\":\"2026-02-17T08:57:36+00:00\",\"dateModified\":\"2026-02-17T08:57:57+00:00\",\"description\":\"A l\u2019occasion de la parution de la seconde \u00e9dition de son manuel de droit luxembourgeois des contrats, et \u00e0 partir de l\u2019exp\u00e9rience que la r\u00e9daction de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/#primaryimage\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2025\/01\/AdobeStock_575311679-scaled.jpeg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2025\/01\/AdobeStock_575311679-scaled.jpeg\",\"width\":2560,\"height\":921,\"caption\":\"Business Financing Accounting Banking Concept, Businesswoman doing finances and calculating financial report with business graph growth cahrt, finance and investment concept\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uni.lu\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facult\u00e9 de Droit, d\u2019\u00c9conomie et de Finance\",\"item\":\"https:\/\/www.uni.lu\/fdef-fr\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Events\",\"item\":\"https:\/\/www.uni.lu\/fdef-fr\/events\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"R\u00e9flexions sur la jurisprudence civile au Luxembourg. L\u2019exemple du droit des contrats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uni.lu\/fdef-fr\/#website\",\"url\":\"https:\/\/www.uni.lu\/fdef-fr\/\",\"name\":\"FDEF\",\"description\":\"Facult\u00e9 de Droit, d\u2019\u00c9conomie et de Finance I Uni.lu\",\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/fdef-fr\/#organization\"},\"alternateName\":\"Facult\u00e9 de Droit, d\u2019\u00c9conomie et de Finance I Universit\u00e9 du Luxembourg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uni.lu\/fdef-fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.uni.lu\/fdef-fr\/#organization\",\"name\":\"FDEF - Universit\u00e9 du Luxembourg I Uni.lu\",\"alternateName\":\"Facult\u00e9 de Droit, d\u2019\u00c9conomie et de Finance\",\"url\":\"https:\/\/www.uni.lu\/fdef-fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.uni.lu\/fdef-fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2026\/03\/03111953\/FDEF_SM-Profile_1600x1600px-scaled.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2026\/03\/03111953\/FDEF_SM-Profile_1600x1600px-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"FDEF - Universit\u00e9 du Luxembourg I Uni.lu\"},\"image\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2026\/04\/24144332\/20200609-Belval-Campus_Henri-Goergen-23.jpg\",\"sameAs\":[\"https:\/\/www.facebook.com\/uni.FDEF.lu\",\"https:\/\/www.linkedin.com\/showcase\/fdef-uni-lu\/\"],\"email\":\"communication@uni.lu\",\"telephone\":\"+3524666441\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"2, place de l\u2019Universit\u00e9\",\"addressLocality\":\"Esch-sur-Alzette\",\"postalCode\":\"4365\",\"addressCountry\":\"LU\"},\"description\":\"Facult\u00e9 de Droit, d\u2019\u00c9conomie et de Finance I Uni.lu\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"R\u00e9flexions sur la jurisprudence civile au Luxembourg. L\u2019exemple du droit des contrats - FDEF I Uni.lu","description":"A l\u2019occasion de la parution de la seconde \u00e9dition de son manuel de droit luxembourgeois des contrats, et \u00e0 partir de l\u2019exp\u00e9rience que la r\u00e9daction de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9flexions sur la jurisprudence civile au Luxembourg. L\u2019exemple du droit des contrats","og_description":"A l\u2019occasion de la parution de la seconde \u00e9dition de son manuel de droit luxembourgeois des contrats, et \u00e0 partir de l\u2019exp\u00e9rience que la r\u00e9daction de","og_url":"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/","og_site_name":"FDEF FR","article_publisher":"https:\/\/www.facebook.com\/uni.FDEF.lu","article_modified_time":"2026-02-17T08:57:57+00:00","og_image":[{"width":2560,"height":921,"url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2025\/01\/AdobeStock_575311679-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/","url":"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/","name":"R\u00e9flexions sur la jurisprudence civile au Luxembourg. L\u2019exemple du droit des contrats - FDEF I Uni.lu","isPartOf":{"@id":"https:\/\/www.uni.lu\/fdef-fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/#primaryimage"},"image":{"@id":"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2025\/01\/AdobeStock_575311679-scaled.jpeg","datePublished":"2026-02-17T08:57:36+00:00","dateModified":"2026-02-17T08:57:57+00:00","description":"A l\u2019occasion de la parution de la seconde \u00e9dition de son manuel de droit luxembourgeois des contrats, et \u00e0 partir de l\u2019exp\u00e9rience que la r\u00e9daction de","breadcrumb":{"@id":"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/#primaryimage","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2025\/01\/AdobeStock_575311679-scaled.jpeg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2025\/01\/AdobeStock_575311679-scaled.jpeg","width":2560,"height":921,"caption":"Business Financing Accounting Banking Concept, Businesswoman doing finances and calculating financial report with business graph growth cahrt, finance and investment concept"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uni.lu\/fdef-fr\/events\/reflexions-sur-la-jurisprudence-civile-au-luxembourg-lexemple-du-droit-des-contrats-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uni.lu\/fr"},{"@type":"ListItem","position":2,"name":"Facult\u00e9 de Droit, d\u2019\u00c9conomie et de Finance","item":"https:\/\/www.uni.lu\/fdef-fr\/"},{"@type":"ListItem","position":3,"name":"Events","item":"https:\/\/www.uni.lu\/fdef-fr\/events\/"},{"@type":"ListItem","position":4,"name":"R\u00e9flexions sur la jurisprudence civile au Luxembourg. L\u2019exemple du droit des contrats"}]},{"@type":"WebSite","@id":"https:\/\/www.uni.lu\/fdef-fr\/#website","url":"https:\/\/www.uni.lu\/fdef-fr\/","name":"FDEF","description":"Facult\u00e9 de Droit, d\u2019\u00c9conomie et de Finance I Uni.lu","publisher":{"@id":"https:\/\/www.uni.lu\/fdef-fr\/#organization"},"alternateName":"Facult\u00e9 de Droit, d\u2019\u00c9conomie et de Finance I Universit\u00e9 du Luxembourg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uni.lu\/fdef-fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.uni.lu\/fdef-fr\/#organization","name":"FDEF - Universit\u00e9 du Luxembourg I Uni.lu","alternateName":"Facult\u00e9 de Droit, d\u2019\u00c9conomie et de Finance","url":"https:\/\/www.uni.lu\/fdef-fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uni.lu\/fdef-fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2026\/03\/03111953\/FDEF_SM-Profile_1600x1600px-scaled.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2026\/03\/03111953\/FDEF_SM-Profile_1600x1600px-scaled.jpg","width":2560,"height":2560,"caption":"FDEF - Universit\u00e9 du Luxembourg I Uni.lu"},"image":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/18\/2026\/04\/24144332\/20200609-Belval-Campus_Henri-Goergen-23.jpg","sameAs":["https:\/\/www.facebook.com\/uni.FDEF.lu","https:\/\/www.linkedin.com\/showcase\/fdef-uni-lu\/"],"email":"communication@uni.lu","telephone":"+3524666441","address":{"@type":"PostalAddress","streetAddress":"2, place de l\u2019Universit\u00e9","addressLocality":"Esch-sur-Alzette","postalCode":"4365","addressCountry":"LU"},"description":"Facult\u00e9 de Droit, d\u2019\u00c9conomie et de Finance I Uni.lu"}]}},"_links":{"self":[{"href":"https:\/\/www.uni.lu\/fdef-fr\/wp-json\/wp\/v2\/events\/3280"}],"collection":[{"href":"https:\/\/www.uni.lu\/fdef-fr\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/www.uni.lu\/fdef-fr\/wp-json\/wp\/v2\/types\/events"}],"author":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fdef-fr\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fdef-fr\/wp-json\/wp\/v2\/comments?post=3280"}],"version-history":[{"count":3,"href":"https:\/\/www.uni.lu\/fdef-fr\/wp-json\/wp\/v2\/events\/3280\/revisions"}],"predecessor-version":[{"id":3284,"href":"https:\/\/www.uni.lu\/fdef-fr\/wp-json\/wp\/v2\/events\/3280\/revisions\/3284"}],"wp:authorship":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fdef-fr\/wp-json\/wp\/v2\/users\/85"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/fdef-fr\/wp-json\/wp\/v2\/media\/2746"}],"wp:attachment":[{"href":"https:\/\/www.uni.lu\/fdef-fr\/wp-json\/wp\/v2\/media?parent=3280"}],"wp:term":[{"taxonomy":"events-topic","embeddable":true,"href":"https:\/\/www.uni.lu\/fdef-fr\/wp-json\/wp\/v2\/events-topic?post=3280"},{"taxonomy":"events-type","embeddable":true,"href":"https:\/\/www.uni.lu\/fdef-fr\/wp-json\/wp\/v2\/events-type?post=3280"},{"taxonomy":"organisation","embeddable":true,"href":"https:\/\/www.uni.lu\/fdef-fr\/wp-json\/wp\/v2\/organisation?post=3280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}