{"id":400,"date":"2020-03-10T14:58:03","date_gmt":"2020-03-10T14:58:03","guid":{"rendered":"https:\/\/website.prod.unilu.spikeseed.cloud\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/"},"modified":"2020-03-10T14:58:03","modified_gmt":"2020-03-10T14:58:03","slug":"zwei-doktorarbeiten-zwischen-geist-und-informatik","status":"publish","type":"news","link":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/","title":{"rendered":"Zwei Doktorarbeiten zwischen Geist und Informatik"},"content":{"rendered":"<section class=\"wp-block-unilux-blocks-free-section section\"><div class=\"container xl:max-w-screen-xl\"><p>In den vergangenen Wochen haben zwei Doktorandinnen Ihre wissenschaftlichen Arbeiten pr\u00e4sentiert und sich den Fragen und Anregungen der f\u00fcnfk\u00f6pfigen internationalen Expertenkommission gestellt.<\/p><p>von <a href=\"https:\/\/wwwde.uni.lu\/recherche\/fstm\/interdisciplinary_lab_for_intelligent_and_adaptive_systems_ilias\/members\/christoph_schommer\" target=\"_self\" title=\"\" rel=\"noopener\">Christoph Schommer<\/a><\/p><p>Eine Doktorarbeit anzufertigen erfordert neben Disziplin, Ausdauer und st\u00e4ndiger wissenschaftlicher Neugier auch ein geh\u00f6riges Ma\u00df an Flei\u00df. Des Weiteren muss die F\u00e4higkeit, wissenschaftliche Inhalte zu Papier zu bringen bzw. auch zu pr\u00e4sentieren, vorhanden sein. Eine Doktorarbeit kann letztendlich nur dann eingereicht und verteidigt werden, wenn das zust\u00e4ndige Doktoratskommittee dies beschlie\u00dft. Die Zeit zum Anfertigen einer Arbeit betr\u00e4gt zwischen drei und vier Jahren.<\/p><p>Ich m\u00f6chte an dieser Stelle die Arbeiten zweier junger Wissenschaftler vorstellen, die vorbildliche Forschung veranschaulichen: Einerseits Frau <a href=\"https:\/\/wwwde.uni.lu\/recherche\/fhse\/lucet\/people2\/tahereh_pazouki\" target=\"_self\" title=\"\" rel=\"noopener\">Dr Tahereh Pazouki<\/a> vom <a href=\"https:\/\/wwwde.uni.lu\/recherche\/fhse\/lucet\" target=\"_self\" title=\"\" rel=\"noopener\">Luxembourg Centre for Educational Testing<\/a> der Universit\u00e4t Luxembourg, die \u00fcber das System MaGrid, eine sprachneutrale Lehr- und Lernanwendung, promoviert hat. Andererseits Frau <a href=\"https:\/\/wwwde.uni.lu\/recherche\/fstm\/dcs\/members\/siwen_guo\" target=\"_self\" title=\"\" rel=\"noopener\">Dr Siwen Guo<\/a> vom <a href=\"https:\/\/wwwde.uni.lu\/fstm\/studies\/computer_science\" target=\"_self\" title=\"\" rel=\"noopener\">Department of Computer Science<\/a>, deren Promotion sich um das Thema \u201eintelligentes Finden von Emotionen in Texten\u201c drehte. W\u00e4hrend Frau Dr Pazouki Ihren Master vom Department of Computer Science erhalten hatte, studierte Frau Dr Guo Computer and Communication Technology an der Universit\u00e4t des Saarlandes in Saarbr\u00fccken.<\/p><p><strong>Sprachbelastung im Rechenkurs reduzieren<\/strong><\/p><p>Tahereh Pazouki motiviert Ihre Arbeit dadurch, dass gute Rechenkenntnisse im Kindesalter ein wichtiger Faktor f\u00fcr die berufliche Karriere, f\u00fcr die Gesundheit und die pers\u00f6nliche Entwicklung eines Kindes ist. Aufgrund des hierarchischen Charakters der wachsenden mathematischen F\u00e4higkeiten sind gerade die Vorschuljahre eine grundlegende Phase, da hier in entscheidender Weise die Bausteine f\u00fcr die zuk\u00fcnftige Erforschung mathematischer Konzepte erlernt werden. Des Weiteren hat die Kenntnis der Unterrichtssprache einen entscheidenden Einfluss auf das Erlernen der Mathematik. Das Erlernen der Mathematik durch Kinder und Heranwachsende, deren Prim\u00e4rsprache sich von der Unterrichtssprache unterscheidet, wirft deswegen einige kritische Fragen auf. Insbesondere gilt das f\u00fcr L\u00e4nder mit heterogenen Populationen und einer hohen Anzahl von Sch\u00fclern mit Migrationshintergrund.<\/p><p>\u201eDa zum Beispiel Luxemburgisch die Unterrichtssprache in den Vorschulklassen ist, stehen die Kinder und ihre Lehrer vor gro\u00dfen Herausforderungen\u201c, so Frau Pazouki.<\/p><p>W\u00e4hrend Ihrer Doktorarbeit an der Universit\u00e4t Luxemburg hat Frau Pazouki versucht, die genannten Probleme im Einklang mit dem Lehren und Lernen fr\u00fcher mathematischer F\u00e4higkeiten anzugehen. So entwickelte sie das Softwareprodukt \u201eMaGrid\u201c, was eine sprachneutrale Lehr- und Lernanwendung, die die fr\u00fchen mathematischen F\u00e4higkeiten der Sch\u00fclerinnen und Sch\u00fcler f\u00f6rdern soll, darstellt. MaGrid stellt Trainingsmaterial und Anweisungen in visueller Form dar und bietet \u201eLearning by doing\u201c-Trainingsaktivit\u00e4ten an. Durch die Verwendung visueller statt verbaler Anweisungen kann die Sprachbelastung reduziert und allen Kindern, unabh\u00e4ngig von ihrem sprachlichen Hintergrund, die M\u00f6glichkeit gegeben werden, von dem Training zu profitieren. Damit wird die Sprachbarriere in der mathematischen Bildung f\u00fcr Zweitsprachler, die in mehrsprachigen Schulen anzutreffen ist, beseitigt.<\/p><figure class=\"wp-block-dev4-reusable-blocks-image  object-fit--contain\">\n    \n<img decoding=\"async\" class=\"wp-block-image unilux-custom-image-block\"\n                alt=\"\"\n            src=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2023\/07\/zwei_doktorarbeiten_zwischen_geist_und_informatik.jpg\"\n                srcset=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2023\/07\/zwei_doktorarbeiten_zwischen_geist_und_informatik-300x166.jpg 300w, https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2023\/07\/zwei_doktorarbeiten_zwischen_geist_und_informatik.jpg 450w\"\n                style=\"object-position: 50.00% 50.00%; font-family: &quot;object-fit: contain; object-position: 50.00% 50.00%;&quot;; aspect-ratio: 16\/9; object-fit: contain; width: 100%;\"\n        loading=\"lazy\"\n\/>            <p class=\"wp-block-dev4-reusable-blocks-image-caption\">\n            Von links nach rechts: Prof. Dr. Christoph Schommer (Universit\u00e4t Luxembourg), Prof. Dr. Korbinian M\u00f6ller (Universit\u00e4t T\u00fcbingen), Prof. Dr. Romain Martin (Minist\u00e8re de l\u2019Enseignement Sup\u00e9rieur et de la recherche), Dr. Tahereh Pazouki, Prof Dr Christine Schiltz (Universit\u00e4t Luxembourg), Prof. Dr. Antoine Fischbach (Universit\u00e4t Luxembourg), and Prof. Dr. Philip Sonnleitner (Universit\u00e4t Luxembourg).        <\/p>\n    <\/figure><p><strong>Ich bin ich, also \u00e4u\u00dfere ich mich<\/strong><\/p><p>Das Ziel der Arbeit von Siwen Guo war es, ein Berechnungsmodell zur Untersuchung der Individualit\u00e4t in der Art und Weise, wie Menschen ihre Meinung \u00e4u\u00dfern, zu konstruieren. Insbesondere werden f\u00fcr die Aufgabe Beitr\u00e4ge aus sozialen Netzwerken (zum Beispiel Twitter) untersucht, die sowohl textliche Informationen (Tweets) als auch kontextuelle Informationen wie die Benutzerinformationen und die Zeitstempel der Beitr\u00e4ge enthalten. Basierend auf diesen Informationen werden hierarchische neuronale Netze eingesetzt, um die sozio-psychologischen Annahmen \u00fcber die Meinungsvielfalt der Menschen zu realisieren.<\/p><p>Das in dieser Arbeit entwickelte Modell zeigt die Bedeutung bei der Durchf\u00fchrung personalisierter Stimmungsanalysen und kann dazu beitragen, das Sprachverst\u00e4ndnis bei verschiedenen verwandten Aufgaben zu verbessern.<\/p><figure class=\"wp-block-dev4-reusable-blocks-image  object-fit--contain\">\n    \n<img decoding=\"async\" class=\"wp-block-image unilux-custom-image-block\"\n                alt=\"\"\n            src=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2023\/07\/zwei_doktorarbeiten_zwischen_geist_und_informatik_bild.png\"\n                srcset=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2023\/07\/zwei_doktorarbeiten_zwischen_geist_und_informatik_bild-300x199.png 300w, https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2023\/07\/zwei_doktorarbeiten_zwischen_geist_und_informatik_bild.png 454w\"\n                style=\"object-position: 50.00% 50.00%; font-family: &quot;object-fit: contain; object-position: 50.00% 50.00%;&quot;; aspect-ratio: 3\/2; object-fit: contain; width: 100%;\"\n        loading=\"lazy\"\n\/>            <p class=\"wp-block-dev4-reusable-blocks-image-caption\">\n            Von links nach rechts: Dr. Kai Hui (Amazon Research Berlin, Alexa Team), Prof. Dr. Leon van der Torre (Universit\u00e4t Luxembourg), Prof. Dr. Christoph Schommer (Universit\u00e4t Luxembourg), Dr. Siwen Guo, Dr Tiansi Dong (Universit\u00e4t Bonn), und Dr. Pouyan Ziafati (LuxAi). Es fehlen: Prof. Dr. Manfred Stede (Universit\u00e4t Potsdam) und Dr. Feiju Xu (Vice-President Lenovo and Head of AI, Beijing, China).        <\/p>\n    <\/figure><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>In den vergangenen Wochen haben zwei Doktorandinnen Ihre wissenschaftlichen Arbeiten pr\u00e4sentiert und sich den Fragen und Anregungen der f\u00fcnfk\u00f6pfigen internationalen Expertenkommission gestellt.<\/p>\n","protected":false},"author":0,"featured_media":401,"template":"","format":"standard","meta":{"featured_image_focal_point":[],"show_featured_caption":false,"ulux_newsletter_groups":"","uluxPostTitle":"","uluxPrePostTitle":"","_trash_the_other_posts":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false},"news-category":[3],"news-topic":[],"organisation":[147,25,226],"authorship":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zwei Doktorarbeiten zwischen Geist und Informatik - Universit\u00e4t Luxemburg<\/title>\n<meta name=\"description\" content=\"In den vergangenen Wochen haben zwei Doktorandinnen Ihre wissenschaftlichen Arbeiten pr\u00e4sentiert und sich den Fragen und Anregungen der f\u00fcnfk\u00f6pfigen internationalen Expertenkommission gestellt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zwei Doktorarbeiten zwischen Geist und Informatik\" \/>\n<meta property=\"og:description\" content=\"In den vergangenen Wochen haben zwei Doktorandinnen Ihre wissenschaftlichen Arbeiten pr\u00e4sentiert und sich den Fragen und Anregungen der f\u00fcnfk\u00f6pfigen internationalen Expertenkommission gestellt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/\" \/>\n<meta property=\"og:site_name\" content=\"UNI DE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uni.lu\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2020\/03\/zwei_doktorarbeiten_zwischen_geist_und_informatik.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Zwei Doktorarbeiten zwischen Geist und Informatik\",\"datePublished\":\"2020-03-10T14:58:03+00:00\",\"dateModified\":\"2020-03-10T14:58:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/\"},\"wordCount\":589,\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2020\/03\/zwei_doktorarbeiten_zwischen_geist_und_informatik.jpg\",\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/\",\"url\":\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/\",\"name\":\"Zwei Doktorarbeiten zwischen Geist und Informatik - Universit\u00e4t Luxemburg\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2020\/03\/zwei_doktorarbeiten_zwischen_geist_und_informatik.jpg\",\"datePublished\":\"2020-03-10T14:58:03+00:00\",\"dateModified\":\"2020-03-10T14:58:03+00:00\",\"description\":\"In den vergangenen Wochen haben zwei Doktorandinnen Ihre wissenschaftlichen Arbeiten pr\u00e4sentiert und sich den Fragen und Anregungen der f\u00fcnfk\u00f6pfigen internationalen Expertenkommission gestellt.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#primaryimage\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2020\/03\/zwei_doktorarbeiten_zwischen_geist_und_informatik.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2020\/03\/zwei_doktorarbeiten_zwischen_geist_und_informatik.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uni.lu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/www.uni.lu\/de\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zwei Doktorarbeiten zwischen Geist und Informatik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uni.lu\/de\/#website\",\"url\":\"https:\/\/www.uni.lu\/de\/\",\"name\":\"Uni.lu\",\"description\":\"Universit\u00e4t Luxemburg\",\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/de\/#organization\"},\"alternateName\":\"Universit\u00e4t Luxemburg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uni.lu\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.uni.lu\/de\/#organization\",\"name\":\"Universit\u00e4t Luxemburg\",\"alternateName\":\"Uni.lu\",\"url\":\"https:\/\/www.uni.lu\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.uni.lu\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2026\/03\/03120000\/UNIV_SM-Profile_1600x1600px-scaled.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2026\/03\/03120000\/UNIV_SM-Profile_1600x1600px-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Universit\u00e4t Luxemburg\"},\"image\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2026\/04\/24144329\/20200609-Belval-Campus_Henri-Goergen-23.jpg\",\"sameAs\":[\"https:\/\/www.facebook.com\/uni.lu\",\"https:\/\/www.linkedin.com\/school\/university-of-luxembourg\/\",\"https:\/\/www.instagram.com\/uni.lu\",\"https:\/\/www.youtube.com\/@uni_lu\",\"https:\/\/en.wikipedia.org\/wiki\/University_of_Luxembourg\"],\"email\":\"communication@uni.lu\",\"telephone\":\"+3524666441\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"2, place de l\u2019Universit\u00e9\",\"addressLocality\":\"Esch-sur-Alzette\",\"postalCode\":\"4365\",\"addressCountry\":\"LU\"},\"description\":\"Universit\u00e4t Luxemburg\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zwei Doktorarbeiten zwischen Geist und Informatik - Universit\u00e4t Luxemburg","description":"In den vergangenen Wochen haben zwei Doktorandinnen Ihre wissenschaftlichen Arbeiten pr\u00e4sentiert und sich den Fragen und Anregungen der f\u00fcnfk\u00f6pfigen internationalen Expertenkommission gestellt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/","og_locale":"de_DE","og_type":"article","og_title":"Zwei Doktorarbeiten zwischen Geist und Informatik","og_description":"In den vergangenen Wochen haben zwei Doktorandinnen Ihre wissenschaftlichen Arbeiten pr\u00e4sentiert und sich den Fragen und Anregungen der f\u00fcnfk\u00f6pfigen internationalen Expertenkommission gestellt.","og_url":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/","og_site_name":"UNI DE","article_publisher":"https:\/\/www.facebook.com\/uni.lu","og_image":[{"width":800,"height":600,"url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2020\/03\/zwei_doktorarbeiten_zwischen_geist_und_informatik.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#article","isPartOf":{"@id":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/"},"author":{"name":"","@id":""},"headline":"Zwei Doktorarbeiten zwischen Geist und Informatik","datePublished":"2020-03-10T14:58:03+00:00","dateModified":"2020-03-10T14:58:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/"},"wordCount":589,"publisher":{"@id":"https:\/\/www.uni.lu\/de\/#organization"},"image":{"@id":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2020\/03\/zwei_doktorarbeiten_zwischen_geist_und_informatik.jpg","inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/","url":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/","name":"Zwei Doktorarbeiten zwischen Geist und Informatik - Universit\u00e4t Luxemburg","isPartOf":{"@id":"https:\/\/www.uni.lu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#primaryimage"},"image":{"@id":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2020\/03\/zwei_doktorarbeiten_zwischen_geist_und_informatik.jpg","datePublished":"2020-03-10T14:58:03+00:00","dateModified":"2020-03-10T14:58:03+00:00","description":"In den vergangenen Wochen haben zwei Doktorandinnen Ihre wissenschaftlichen Arbeiten pr\u00e4sentiert und sich den Fragen und Anregungen der f\u00fcnfk\u00f6pfigen internationalen Expertenkommission gestellt.","breadcrumb":{"@id":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#primaryimage","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2020\/03\/zwei_doktorarbeiten_zwischen_geist_und_informatik.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2020\/03\/zwei_doktorarbeiten_zwischen_geist_und_informatik.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.uni.lu\/de\/news\/zwei-doktorarbeiten-zwischen-geist-und-informatik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uni.lu\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.uni.lu\/de\/news\/"},{"@type":"ListItem","position":3,"name":"Zwei Doktorarbeiten zwischen Geist und Informatik"}]},{"@type":"WebSite","@id":"https:\/\/www.uni.lu\/de\/#website","url":"https:\/\/www.uni.lu\/de\/","name":"Uni.lu","description":"Universit\u00e4t Luxemburg","publisher":{"@id":"https:\/\/www.uni.lu\/de\/#organization"},"alternateName":"Universit\u00e4t Luxemburg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uni.lu\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.uni.lu\/de\/#organization","name":"Universit\u00e4t Luxemburg","alternateName":"Uni.lu","url":"https:\/\/www.uni.lu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.uni.lu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2026\/03\/03120000\/UNIV_SM-Profile_1600x1600px-scaled.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2026\/03\/03120000\/UNIV_SM-Profile_1600x1600px-scaled.jpg","width":2560,"height":2560,"caption":"Universit\u00e4t Luxemburg"},"image":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2026\/04\/24144329\/20200609-Belval-Campus_Henri-Goergen-23.jpg","sameAs":["https:\/\/www.facebook.com\/uni.lu","https:\/\/www.linkedin.com\/school\/university-of-luxembourg\/","https:\/\/www.instagram.com\/uni.lu","https:\/\/www.youtube.com\/@uni_lu","https:\/\/en.wikipedia.org\/wiki\/University_of_Luxembourg"],"email":"communication@uni.lu","telephone":"+3524666441","address":{"@type":"PostalAddress","streetAddress":"2, place de l\u2019Universit\u00e9","addressLocality":"Esch-sur-Alzette","postalCode":"4365","addressCountry":"LU"},"description":"Universit\u00e4t Luxemburg"}]}},"blog_id":10,"_links":{"self":[{"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/news\/400"}],"collection":[{"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":0,"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/news\/400\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/media\/401"}],"wp:attachment":[{"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/media?parent=400"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/news-category?post=400"},{"taxonomy":"news-topic","embeddable":true,"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/news-topic?post=400"},{"taxonomy":"organisation","embeddable":true,"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/organisation?post=400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}