{"id":1063,"date":"2022-11-03T15:47:26","date_gmt":"2022-11-03T15:47:26","guid":{"rendered":"https:\/\/website.prod.unilu.spikeseed.cloud\/de\/news\/erstes-selbstfahrendes-auto-im-luxemburgischen-strassenverkehr\/"},"modified":"2022-11-03T15:47:26","modified_gmt":"2022-11-03T15:47:26","slug":"erstes-selbstfahrendes-auto-im-luxemburgischen-strassenverkehr","status":"publish","type":"news","link":"https:\/\/www.uni.lu\/de\/news\/erstes-selbstfahrendes-auto-im-luxemburgischen-strassenverkehr\/","title":{"rendered":"Erstes selbstfahrendes Auto im luxemburgischen Stra\u00dfenverkehr"},"content":{"rendered":"<section class=\"wp-block-unilux-blocks-free-section section\"><div class=\"container xl:max-w-screen-xl\"><p>Das Interdisciplinary Centre for Security, Reliability and Trust (SnT) der Universit\u00e4t Luxemburg pr\u00e4sentierte heute, am Donnerstag, den 3. November 2022, ein selbstfahrendes Auto im laufenden Stra\u00dfenverkehr auf dem Kirchberg. Dies ist das erste Mal, dass sich ein autonomer PKW mit gew\u00f6hnlichen B\u00fcrgern als Passagieren in den Verkehrsfluss in Luxemburg einreihte.<\/p><p>Das selbstfahrende Auto bietet eine Testumgebung f\u00fcr Navigationstechniken\u00a0und hochaufl\u00f6senden (HD) Karten, die im 360Lab\u00a0des SnT erforscht werden. Die Demonstration stellt den H\u00f6hepunkt von f\u00fcnf Jahren Forschungsarbeit des 360Lab-Teams unter der Leitung von Prof. Dr. Rapha\u00ebl Frank dar. Das 360Lab ist das erste thematische Forschungslabor des Landes, das sich mit \u201esmart mobility\u201c, d.h. intelligenter Mobilit\u00e4t, befasst. Es dient als Rahmen f\u00fcr die Durchf\u00fchrung strategischer und kollaborativer Forschung auf dem breiteren Feld der Mobilit\u00e4t.<\/p><p>Die Forschung des 360Lab ist von zentraler Bedeutung f\u00fcr die Zukunft des autonomen Fahrens in Luxemburg. Entwickelte HD-Karten der Region bieten Informationen, die bisher dem Fahrer auf dem Weg zu seinem Ziel durch Stra\u00dfenschilder und Markierungen vermittelt werden. HD-Karten bilden somit die Grundlage f\u00fcr autonome Navigation.<\/p><p>Sie sind sehr viel detaillierter als die Karten in Standardaufl\u00f6sung (SD), die \u00fcblicherweise von herk\u00f6mmlichen Navigationsdiensten in Autos und mobilen Ger\u00e4ten verwendet werden. Die Karte des Testfahrzeugs wurde in Zusammenarbeit mit dem in San Francisco ans\u00e4ssigen Start-up-Unternehmen Civil Maps erstellt, das sich auf die Bereitstellung von HD-Karten f\u00fcr die automatisierte Mobilit\u00e4t spezialisiert hat.<\/p><p>\u00dcber die fachliche Forschung hinaus ist die Erforschung der autonomen Navigation auch mit zahlreichen logistischen Herausforderungen verbunden. Als Teil der Forschungsarbeit musste das Team auch eine Genehmigung f\u00fcr das Fahren des PKW auf luxemburgischen Stra\u00dfen einholen und damit den Weg f\u00fcr eine gesetzliche Regulierung des autonomen Fahrens im Land ebnen.<\/p><p>\u201eAutonomes Fahren birgt das Potenzial, ein Mobilit\u00e4ts\u00f6kosystem zu erschaffen, das sicherer und nachhaltiger ist. Vollst\u00e4ndige Autonomie wird einen Paradigmenwechsel in der Mobilit\u00e4t bringen, der den Stra\u00dfenverkehr verbessert und Staus durch eine geringere Anzahl von Fahrzeugen reduziert\u201c, so Prof. <a href=\"https:\/\/wwwde.uni.lu\/snt\/people\/raphael_frank\" target=\"_self\" title=\"\" rel=\"noopener\">Rapha\u00ebl Frank<\/a>. \u201eUnsere Aufgabe ist es, eine Forschungsumgebung zu schaffen, in der wir die Technologie der autonomen Mobilit\u00e4t demonstrieren und die wir f\u00fcr Forschung und Lehre nutzen k\u00f6nnen. Mit der heutigen Pr\u00e4sentation wird dieses Ziel erreicht, da die \u00d6ffentlichkeit zum ersten Mal die Funktionsweise des Fahrzeugs aus erster Hand erleben kann.\u201c<\/p>\n<h5 class=\"has-text-align-left wp-block-unilux-blocks-heading\"        id=\"universitaet-luxemburg-christian-wilmes\"\n    >\n\u00a9 Universit\u00e4t Luxemburg \/ Christian Wilmes<\/h5>\n<\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>Das Interdisciplinary Centre for Security, Reliability and Trust (SnT) der Universit\u00e4t Luxemburg pr\u00e4sentierte heute, am Donnerstag, den 3. November 2022, ein selbstfahrendes Auto im laufenden Stra\u00dfenverkehr auf dem Kirchberg. Dies ist das erste Mal, dass sich ein autonomer PKW mit gew\u00f6hnlichen B\u00fcrgern als Passagieren in den Verkehrsfluss in Luxemburg einreihte.<\/p>\n","protected":false},"author":42,"featured_media":1064,"template":"","format":"standard","meta":{"featured_image_focal_point":[],"show_featured_caption":false,"ulux_newsletter_groups":"","uluxPostTitle":"","uluxPrePostTitle":"","_trash_the_other_posts":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false},"news-category":[4,3],"news-topic":[],"organisation":[184,226],"authorship":[42],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Erstes selbstfahrendes Auto im luxemburgischen Stra\u00dfenverkehr - Universit\u00e4t Luxemburg<\/title>\n<meta name=\"description\" content=\"Das Interdisciplinary Centre for Security, Reliability and Trust (SnT) der Universit\u00e4t Luxemburg pr\u00e4sentierte heute, am Donnerstag, den 3. November 2022, ein selbstfahrendes Auto im laufenden Stra\u00dfenverkehr auf dem Kirchberg. Dies ist das erste Mal, dass sich ein autonomer PKW mit gew\u00f6hnlichen B\u00fcrgern als Passagieren in den Verkehrsfluss in Luxemburg einreihte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uni.lu\/de\/news\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erstes selbstfahrendes Auto im luxemburgischen Stra\u00dfenverkehr\" \/>\n<meta property=\"og:description\" content=\"Das Interdisciplinary Centre for Security, Reliability and Trust (SnT) der Universit\u00e4t Luxemburg pr\u00e4sentierte heute, am Donnerstag, den 3. November 2022, ein selbstfahrendes Auto im laufenden Stra\u00dfenverkehr auf dem Kirchberg. Dies ist das erste Mal, dass sich ein autonomer PKW mit gew\u00f6hnlichen B\u00fcrgern als Passagieren in den Verkehrsfluss in Luxemburg einreihte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uni.lu\/de\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"UNI DE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uni.lu\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2022\/11\/premiere_voiture_autonome_dans_le_trafic_luxembourgeois.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.uni.lu\/de\/news\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/de\/news\/\"},\"author\":{\"name\":\"svankelst\",\"@id\":\"https:\/\/www.uni.lu\/de\/#\/schema\/person\/bbacc9db2c68a323b1a3cbdab743cd0c\"},\"headline\":\"Erstes selbstfahrendes Auto im luxemburgischen Stra\u00dfenverkehr\",\"datePublished\":\"2022-11-03T15:47:26+00:00\",\"dateModified\":\"2022-11-03T15:47:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/de\/news\/\"},\"wordCount\":404,\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/de\/news\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2022\/11\/premiere_voiture_autonome_dans_le_trafic_luxembourgeois.jpg\",\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uni.lu\/de\/news\/\",\"url\":\"https:\/\/www.uni.lu\/de\/news\/\",\"name\":\"Erstes selbstfahrendes Auto im luxemburgischen Stra\u00dfenverkehr - Universit\u00e4t Luxemburg\",\"isPartOf\":{\"@id\":\"https:\/\/www.uni.lu\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uni.lu\/de\/news\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uni.lu\/de\/news\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2022\/11\/premiere_voiture_autonome_dans_le_trafic_luxembourgeois.jpg\",\"datePublished\":\"2022-11-03T15:47:26+00:00\",\"dateModified\":\"2022-11-03T15:47:26+00:00\",\"description\":\"Das Interdisciplinary Centre for Security, Reliability and Trust (SnT) der Universit\u00e4t Luxemburg pr\u00e4sentierte heute, am Donnerstag, den 3. November 2022, ein selbstfahrendes Auto im laufenden Stra\u00dfenverkehr auf dem Kirchberg. Dies ist das erste Mal, dass sich ein autonomer PKW mit gew\u00f6hnlichen B\u00fcrgern als Passagieren in den Verkehrsfluss in Luxemburg einreihte.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uni.lu\/de\/news\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uni.lu\/de\/news\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.uni.lu\/de\/news\/#primaryimage\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2022\/11\/premiere_voiture_autonome_dans_le_trafic_luxembourgeois.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2022\/11\/premiere_voiture_autonome_dans_le_trafic_luxembourgeois.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uni.lu\/de\/news\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uni.lu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/www.uni.lu\/de\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Erstes selbstfahrendes Auto im luxemburgischen Stra\u00dfenverkehr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uni.lu\/de\/#website\",\"url\":\"https:\/\/www.uni.lu\/de\/\",\"name\":\"Uni.lu\",\"description\":\"Universit\u00e4t Luxemburg\",\"publisher\":{\"@id\":\"https:\/\/www.uni.lu\/de\/#organization\"},\"alternateName\":\"Universit\u00e4t Luxemburg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uni.lu\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.uni.lu\/de\/#organization\",\"name\":\"Universit\u00e4t Luxemburg\",\"alternateName\":\"Uni.lu\",\"url\":\"https:\/\/www.uni.lu\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.uni.lu\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2026\/03\/03120000\/UNIV_SM-Profile_1600x1600px-scaled.jpg\",\"contentUrl\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2026\/03\/03120000\/UNIV_SM-Profile_1600x1600px-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Universit\u00e4t Luxemburg\"},\"image\":\"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2026\/04\/24144329\/20200609-Belval-Campus_Henri-Goergen-23.jpg\",\"sameAs\":[\"https:\/\/www.facebook.com\/uni.lu\",\"https:\/\/www.linkedin.com\/school\/university-of-luxembourg\/\",\"https:\/\/www.instagram.com\/uni.lu\",\"https:\/\/www.youtube.com\/@uni_lu\",\"https:\/\/en.wikipedia.org\/wiki\/University_of_Luxembourg\"],\"email\":\"communication@uni.lu\",\"telephone\":\"+3524666441\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"2, place de l\u2019Universit\u00e9\",\"addressLocality\":\"Esch-sur-Alzette\",\"postalCode\":\"4365\",\"addressCountry\":\"LU\"},\"description\":\"Universit\u00e4t Luxemburg\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uni.lu\/de\/#\/schema\/person\/bbacc9db2c68a323b1a3cbdab743cd0c\",\"name\":\"svankelst\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.uni.lu\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/54b090610f90377561821e2f82f83b9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/54b090610f90377561821e2f82f83b9f?s=96&d=mm&r=g\",\"caption\":\"svankelst\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Erstes selbstfahrendes Auto im luxemburgischen Stra\u00dfenverkehr - Universit\u00e4t Luxemburg","description":"Das Interdisciplinary Centre for Security, Reliability and Trust (SnT) der Universit\u00e4t Luxemburg pr\u00e4sentierte heute, am Donnerstag, den 3. November 2022, ein selbstfahrendes Auto im laufenden Stra\u00dfenverkehr auf dem Kirchberg. Dies ist das erste Mal, dass sich ein autonomer PKW mit gew\u00f6hnlichen B\u00fcrgern als Passagieren in den Verkehrsfluss in Luxemburg einreihte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uni.lu\/de\/news\/","og_locale":"de_DE","og_type":"article","og_title":"Erstes selbstfahrendes Auto im luxemburgischen Stra\u00dfenverkehr","og_description":"Das Interdisciplinary Centre for Security, Reliability and Trust (SnT) der Universit\u00e4t Luxemburg pr\u00e4sentierte heute, am Donnerstag, den 3. November 2022, ein selbstfahrendes Auto im laufenden Stra\u00dfenverkehr auf dem Kirchberg. Dies ist das erste Mal, dass sich ein autonomer PKW mit gew\u00f6hnlichen B\u00fcrgern als Passagieren in den Verkehrsfluss in Luxemburg einreihte.","og_url":"https:\/\/www.uni.lu\/de\/news\/","og_site_name":"UNI DE","article_publisher":"https:\/\/www.facebook.com\/uni.lu","og_image":[{"width":800,"height":600,"url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2022\/11\/premiere_voiture_autonome_dans_le_trafic_luxembourgeois.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.uni.lu\/de\/news\/#article","isPartOf":{"@id":"https:\/\/www.uni.lu\/de\/news\/"},"author":{"name":"svankelst","@id":"https:\/\/www.uni.lu\/de\/#\/schema\/person\/bbacc9db2c68a323b1a3cbdab743cd0c"},"headline":"Erstes selbstfahrendes Auto im luxemburgischen Stra\u00dfenverkehr","datePublished":"2022-11-03T15:47:26+00:00","dateModified":"2022-11-03T15:47:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uni.lu\/de\/news\/"},"wordCount":404,"publisher":{"@id":"https:\/\/www.uni.lu\/de\/#organization"},"image":{"@id":"https:\/\/www.uni.lu\/de\/news\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2022\/11\/premiere_voiture_autonome_dans_le_trafic_luxembourgeois.jpg","inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.uni.lu\/de\/news\/","url":"https:\/\/www.uni.lu\/de\/news\/","name":"Erstes selbstfahrendes Auto im luxemburgischen Stra\u00dfenverkehr - Universit\u00e4t Luxemburg","isPartOf":{"@id":"https:\/\/www.uni.lu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uni.lu\/de\/news\/#primaryimage"},"image":{"@id":"https:\/\/www.uni.lu\/de\/news\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2022\/11\/premiere_voiture_autonome_dans_le_trafic_luxembourgeois.jpg","datePublished":"2022-11-03T15:47:26+00:00","dateModified":"2022-11-03T15:47:26+00:00","description":"Das Interdisciplinary Centre for Security, Reliability and Trust (SnT) der Universit\u00e4t Luxemburg pr\u00e4sentierte heute, am Donnerstag, den 3. November 2022, ein selbstfahrendes Auto im laufenden Stra\u00dfenverkehr auf dem Kirchberg. Dies ist das erste Mal, dass sich ein autonomer PKW mit gew\u00f6hnlichen B\u00fcrgern als Passagieren in den Verkehrsfluss in Luxemburg einreihte.","breadcrumb":{"@id":"https:\/\/www.uni.lu\/de\/news\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uni.lu\/de\/news\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.uni.lu\/de\/news\/#primaryimage","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2022\/11\/premiere_voiture_autonome_dans_le_trafic_luxembourgeois.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2022\/11\/premiere_voiture_autonome_dans_le_trafic_luxembourgeois.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.uni.lu\/de\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uni.lu\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.uni.lu\/de\/news\/"},{"@type":"ListItem","position":3,"name":"Erstes selbstfahrendes Auto im luxemburgischen Stra\u00dfenverkehr"}]},{"@type":"WebSite","@id":"https:\/\/www.uni.lu\/de\/#website","url":"https:\/\/www.uni.lu\/de\/","name":"Uni.lu","description":"Universit\u00e4t Luxemburg","publisher":{"@id":"https:\/\/www.uni.lu\/de\/#organization"},"alternateName":"Universit\u00e4t Luxemburg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uni.lu\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.uni.lu\/de\/#organization","name":"Universit\u00e4t Luxemburg","alternateName":"Uni.lu","url":"https:\/\/www.uni.lu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.uni.lu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2026\/03\/03120000\/UNIV_SM-Profile_1600x1600px-scaled.jpg","contentUrl":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2026\/03\/03120000\/UNIV_SM-Profile_1600x1600px-scaled.jpg","width":2560,"height":2560,"caption":"Universit\u00e4t Luxemburg"},"image":"https:\/\/www.uni.lu\/wp-content\/uploads\/sites\/10\/2026\/04\/24144329\/20200609-Belval-Campus_Henri-Goergen-23.jpg","sameAs":["https:\/\/www.facebook.com\/uni.lu","https:\/\/www.linkedin.com\/school\/university-of-luxembourg\/","https:\/\/www.instagram.com\/uni.lu","https:\/\/www.youtube.com\/@uni_lu","https:\/\/en.wikipedia.org\/wiki\/University_of_Luxembourg"],"email":"communication@uni.lu","telephone":"+3524666441","address":{"@type":"PostalAddress","streetAddress":"2, place de l\u2019Universit\u00e9","addressLocality":"Esch-sur-Alzette","postalCode":"4365","addressCountry":"LU"},"description":"Universit\u00e4t Luxemburg"},{"@type":"Person","@id":"https:\/\/www.uni.lu\/de\/#\/schema\/person\/bbacc9db2c68a323b1a3cbdab743cd0c","name":"svankelst","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.uni.lu\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/54b090610f90377561821e2f82f83b9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54b090610f90377561821e2f82f83b9f?s=96&d=mm&r=g","caption":"svankelst"}}]}},"blog_id":10,"_links":{"self":[{"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/news\/1063"}],"collection":[{"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/users\/42"}],"version-history":[{"count":1,"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/news\/1063\/revisions"}],"predecessor-version":[{"id":4301,"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/news\/1063\/revisions\/4301"}],"wp:authorship":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/users\/42"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/media\/1064"}],"wp:attachment":[{"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/media?parent=1063"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/news-category?post=1063"},{"taxonomy":"news-topic","embeddable":true,"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/news-topic?post=1063"},{"taxonomy":"organisation","embeddable":true,"href":"https:\/\/www.uni.lu\/de\/wp-json\/wp\/v2\/organisation?post=1063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}